{"id":48,"count":1,"description":"","link":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/","name":"Cuba","slug":"cuba","taxonomy":"category","parent":47,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuba Archives &#8212; Laylita&#039;s Travels<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuba Archives &#8212; Laylita&#039;s Travels\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/\" \/>\n<meta property=\"og:site_name\" content=\"Laylita&#039;s Travels\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laylita.com\/travel\/wp-content\/uploads\/2015\/04\/Laylita-Travel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/category\\\/latin-america\\\/caribbean\\\/cuba\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/category\\\/latin-america\\\/caribbean\\\/cuba\\\/\",\"name\":\"Cuba Archives &#8212; Laylita&#039;s Travels\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/category\\\/latin-america\\\/caribbean\\\/cuba\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/category\\\/latin-america\\\/caribbean\\\/cuba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Latin America\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/category\\\/latin-america\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caribbean\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/category\\\/latin-america\\\/caribbean\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cuba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/#website\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/\",\"name\":\"Laylita&#039;s Travels\",\"description\":\"Travels and adventures of a modern day nomad\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/#organization\",\"name\":\"Laylita.com\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LAY512x512.png\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/LAY512x512.png\",\"width\":512,\"height\":512,\"caption\":\"Laylita.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/travel\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LaylitaCom\",\"https:\\\/\\\/x.com\\\/laylita\",\"https:\\\/\\\/instagram.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvNX-qrEsv2vNNzG2KXSRag\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuba Archives &#8212; Laylita&#039;s Travels","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/","og_locale":"en_US","og_type":"article","og_title":"Cuba Archives &#8212; Laylita&#039;s Travels","og_url":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/","og_site_name":"Laylita&#039;s Travels","og_image":[{"width":800,"height":799,"url":"https:\/\/www.laylita.com\/travel\/wp-content\/uploads\/2015\/04\/Laylita-Travel.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/","url":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/","name":"Cuba Archives &#8212; Laylita&#039;s Travels","isPartOf":{"@id":"https:\/\/www.laylita.com\/travel\/#website"},"breadcrumb":{"@id":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/cuba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.laylita.com\/travel\/"},{"@type":"ListItem","position":2,"name":"Latin America","item":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/"},{"@type":"ListItem","position":3,"name":"Caribbean","item":"https:\/\/www.laylita.com\/travel\/category\/latin-america\/caribbean\/"},{"@type":"ListItem","position":4,"name":"Cuba"}]},{"@type":"WebSite","@id":"https:\/\/www.laylita.com\/travel\/#website","url":"https:\/\/www.laylita.com\/travel\/","name":"Laylita&#039;s Travels","description":"Travels and adventures of a modern day nomad","publisher":{"@id":"https:\/\/www.laylita.com\/travel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laylita.com\/travel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.laylita.com\/travel\/#organization","name":"Laylita.com","url":"https:\/\/www.laylita.com\/travel\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.laylita.com\/travel\/#\/schema\/logo\/image\/","url":"https:\/\/www.laylita.com\/travel\/wp-content\/uploads\/2016\/08\/LAY512x512.png","contentUrl":"https:\/\/www.laylita.com\/travel\/wp-content\/uploads\/2016\/08\/LAY512x512.png","width":512,"height":512,"caption":"Laylita.com"},"image":{"@id":"https:\/\/www.laylita.com\/travel\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LaylitaCom","https:\/\/x.com\/laylita","https:\/\/instagram.com\/laylapujol\/","https:\/\/www.pinterest.com\/laylapujol\/","https:\/\/www.youtube.com\/channel\/UCvNX-qrEsv2vNNzG2KXSRag"]}]}},"_links":{"self":[{"href":"https:\/\/www.laylita.com\/travel\/wp-json\/wp\/v2\/categories\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laylita.com\/travel\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.laylita.com\/travel\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/travel\/wp-json\/wp\/v2\/categories\/47"}],"wp:post_type":[{"href":"https:\/\/www.laylita.com\/travel\/wp-json\/wp\/v2\/posts?categories=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}