{"id":3457,"date":"2017-04-11T13:32:56","date_gmt":"2017-04-11T20:32:56","guid":{"rendered":"https:\/\/www.laylita.com\/recettes\/?p=3457"},"modified":"2026-01-13T15:43:37","modified_gmt":"2026-01-13T14:43:37","slug":"comment-faire-crepes-sucrees","status":"publish","type":"post","link":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/","title":{"rendered":"Comment faire les cr\u00eapes sucr\u00e9es"},"content":{"rendered":"<p><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3463 size-full\" title=\"Faire les cr\u00eapes sucr\u00e9es\" src=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg\" alt=\"Faire les cr\u00eapes sucr\u00e9es\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg 800w, https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees-640x426.jpg 640w, https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>C&rsquo;est la recette de mon mari pour r\u00e9ussir les cr\u00eapes. &nbsp;Il pr\u00e9pare une pate avec de la farine, du sucre, des \u0153ufs, du lait, de la vanille et du beurre. Avant de rencontrer Nicolas je pensais que faire les cr\u00eapes \u00e9tait compliqu\u00e9 et une chose qu&rsquo;on commanderait plut\u00f4t au restaurant ou en cr\u00eaperie (nous habitons aux Etats Unis, celles ci sont connues ici mais bien moins r\u00e9pandues qu&rsquo;en France). Je me rappelle aussi que lors d&rsquo;un des premiers voyages en France la s\u0153ur de Nicolas, Caroline, qui avait \u00e0 l&rsquo;\u00e9poque juste 12 ou 13 ans, avait fait les cr\u00eapes. Elle les faisait sauter comme une professionnelle.<\/p>\n\n\n<!--more-->\n\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3464 size-full\" title=\"Comment pr\u00e9parer la p\u00e2te \u00e0 cr\u00eapes sucr\u00e9es\" src=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/preparer-pate-a-crepes-sucrees.jpg\" alt=\"Comment pr\u00e9parer la p\u00e2te \u00e0 cr\u00eapes sucr\u00e9es\" width=\"800\" height=\"1200\" srcset=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/preparer-pate-a-crepes-sucrees.jpg 800w, https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/preparer-pate-a-crepes-sucrees-427x640.jpg 427w, https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/preparer-pate-a-crepes-sucrees-768x1152.jpg 768w, https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/preparer-pate-a-crepes-sucrees-683x1024.jpg 683w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>J&rsquo;ai alors r\u00e9alis\u00e9 que faire les cr\u00eapes faisaient partie de la culture fran\u00e7aise. Alors du coup j&rsquo;ai imm\u00e9diatement demand\u00e9 \u00e0 Nico de devenir le cr\u00eapier maison, alors que je continue ma sp\u00e9cialit\u00e9 de faire les ceviches et les empanadas et autres plats d&rsquo;Am\u00e9rique latine. Je les ai faites une fois ou deux, juste pour ajouter \u00e7a \u00e0 ma liste de recettes compl\u00e9t\u00e9es. Mais je dois dire que Nico est plus efficace sur le processus et la cuisson. Il utilise souvent deux po\u00eales en parall\u00e8le pour pr\u00e9parer une plus grande quantit\u00e9 de cr\u00eapes en deux fois moins de temps. Le truc dans ce cas l\u00e0, c&rsquo;est de garder l&rsquo;attention sur deux po\u00eales en m\u00eame temps et \u00e9viter qu&rsquo;une des cr\u00eapes ne br\u00fble. On mange nos cr\u00eapes sal\u00e9es, sucr\u00e9es, avec \u00e9videmment une option sud Am\u00e9ricaine de dulce de leche (confiture de lait, caramel).<\/p>\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-4405\" class=\"wprm-recipe-container\" data-recipe-id=\"4405\" data-servings=\"24\"><div class=\"wprm-recipe wprm-recipe-template-cutout-v2\"><div class=\"wprm-recipe-image wprm-block-image-circle\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 10px;border-style: solid;border-color: #ffffff;\" width=\"200\" height=\"133\" src=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg\" class=\"attachment-200x200 size-200x200\" alt=\"P\u00e2te \u00e0 cr\u00eapes sucr\u00e9es\" srcset=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg 800w, https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees-640x426.jpg 640w, https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees-768x512.jpg 768w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/div>\n<div class=\"wprm-recipe-template-cutout-v2-container\">\n\t<div class=\"wprm-recipe-template-cutout-v2-header\">\n\t\t<h2 class=\"wprm-recipe-name wprm-block-text-bold\">Comment faire les cr\u00eapes sucr\u00e9es<\/h2>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<div class=\"wprm-recipe-summary wprm-block-text-normal\">Recette traditionnelle des cr\u00eapes sucr\u00e9es pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.<\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<style>#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-full svg * { fill: #f8e71c; }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-33 svg * { fill: url(#wprm-recipe-user-rating-0-33); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-50 svg * { fill: url(#wprm-recipe-user-rating-0-50); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-66 svg * { fill: url(#wprm-recipe-user-rating-0-66); }linearGradient#wprm-recipe-user-rating-0-33 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-50 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-66 stop { stop-color: #f8e71c; }<\/style><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"0\" height=\"0\" style=\"display:block;width:0px;height:0px\"><defs><linearGradient id=\"wprm-recipe-user-rating-0-33\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-50\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-66\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><\/svg><div id=\"wprm-recipe-user-rating-0\" class=\"wprm-recipe-rating wprm-recipe-rating-recipe-4405 wprm-user-rating wprm-recipe-rating-separate wprm-user-rating-not-voted wprm-user-rating-allowed\" data-recipe=\"4405\" data-average=\"4.66\" data-count=\"20\" data-total=\"93\" data-user=\"0\" data-decimals=\"2\"data-modal-uid=\"user-rating\"><span class=\"wprm-rating-star wprm-rating-star-1 wprm-rating-star-full\" data-rating=\"1\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 1 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-2 wprm-rating-star-full\" data-rating=\"2\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 2 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-3 wprm-rating-star-full\" data-rating=\"3\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 3 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-4 wprm-rating-star-full\" data-rating=\"4\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 4 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-5 wprm-rating-star-full\" data-rating=\"5\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Rate this recipe 5 out of 5 stars\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><div class=\"wprm-recipe-rating-details wprm-block-text-normal\"><span class=\"wprm-recipe-rating-average\">4.66<\/span> from <span class=\"wprm-recipe-rating-count\">20<\/span> votes<\/div><\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<a href=\"https:\/\/www.laylita.com\/recettes\/wprm_print\/comment-faire-les-crepes-sucrees\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal wprm-recipe-print-inline-button wprm-recipe-link-inline-button wprm-color-accent\" data-recipe-id=\"4405\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Imprimer<\/a>\n\t\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.laylita.com%2Frecettes%2Fcomment-faire-crepes-sucrees%2F&amp;media=https%3A%2F%2Fwww.laylita.com%2Frecettes%2Fwp-content%2Fuploads%2F2017%2F04%2Ffaire-crepes-sucrees.jpg&amp;description=Comment+faire+les+cr%C3%AApes+sucr%C3%A9es&amp;is_video=false\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"4405\" data-url=\"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/\" data-media=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg\" data-description=\"Comment faire les cr\u00eapes sucr\u00e9es\" data-repin=\"\" role=\"button\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal wprm-recipe-pin-inline-button wprm-recipe-link-inline-button wprm-color-accent\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pinterest<\/a>\n\t\t<a href=\"#commentform\" class=\"wprm-recipe-jump-to-comments wprm-recipe-link wprm-block-text-normal wprm-recipe-jump-to-comments-inline-button wprm-recipe-link-inline-button wprm-color-accent\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\"><span class=\"wprm-recipe-icon wprm-recipe-jump-to-comments-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 16 16\" xml:space=\"preserve\" width=\"16\" height=\"16\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><polygon data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" points=\" 13,0.5 15.5,3 7.5,11 4,12 5,8.5 \"><\/polygon> <line data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" x1=\"11\" y1=\"2.5\" x2=\"13.5\" y2=\"5\"><\/line> <path fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" d=\"M13.5,9.5v5 c0,0.552-0.448,1-1,1h-11c-0.552,0-1-0.448-1-1v-11c0-0.552,0.448-1,1-1h5\"><\/path> <\/g><\/svg><\/span> Ajouter un commentaire<\/a>\n\t\t<div class=\"wprm-spacer\"><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-tags-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-course-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-course-label\">Type de plat: <\/span><span class=\"wprm-recipe-course wprm-block-text-normal\">Dessert, Encas, petit d\u00e9jeuner<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-cuisine-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-cuisine-label\">Cuisine: <\/span><span class=\"wprm-recipe-cuisine wprm-block-text-normal\">Fran\u00e7aise<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-keyword-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-keyword-label\">Mot(s) cl\u00e9: <\/span><span class=\"wprm-recipe-keyword wprm-block-text-normal\">comment faire des cr\u00eapes, pr\u00e9paration des cr\u00eapes<\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-times-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-prep-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-prep-time-label\">Temps de pr\u00e9paration: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">20<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutes<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\" aria-hidden=\"true\">minutes<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-cook-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-cook-time-label\">Temps de cuisson: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-cook_time wprm-recipe-cook_time-minutes\">30<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutes<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-cook_time-unit wprm-recipe-cook_timeunit-minutes\" aria-hidden=\"true\">minutes<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-total-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-total-time-label\">Temps total: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-total_time wprm-recipe-total_time-minutes\">50<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutes<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-total_time-unit wprm-recipe-total_timeunit-minutes\" aria-hidden=\"true\">minutes<\/span><\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-servings-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-servings-label\">Sert: <\/span><span class=\"wprm-recipe-servings-with-unit\"><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-4405 wprm-recipe-servings-adjustable-tooltip wprm-block-text-normal\" data-recipe=\"4405\" aria-label=\"Adjust recipe servings\">24<\/span> <span class=\"wprm-recipe-servings-unit wprm-recipe-details-unit wprm-block-text-normal\">cr\u00eapes<\/span><\/span><\/div>\n\t\t\n\t\t\n\t<\/div>\n\t<div id=\"recipe-4405-ingredients\" class=\"wprm-recipe-ingredients-container wprm-recipe-ingredients-no-images wprm-recipe-4405-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"4405\" data-servings=\"24\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingr\u00e9dients<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">6<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">\u0153ufs<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">220<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">g<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de farine<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">750<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">ml<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de lait<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cuill\u00e8res \u00e0 soupe<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de sucre<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cuill\u00e8re \u00e0 caf\u00e9<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">d'extrait de vanille<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">4<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">cuill\u00e8res \u00e0 soupe<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de beurre fondu<\/span><\/li><\/ul><\/div><div class=\"wprm-recipe-ingredient-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-ingredient-group-name wprm-block-text-bold\"> Suggestions pour la garniture:<\/h4><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Fruits frais: <\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">fraises, myrtilles, m\u00fbres, framboises, bananes, mangues, etc<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Confiture de lait<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Nutella ou autre chocolat en pate<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Confitures de fruits comme la fraise ou autre<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Sucre en poudre<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Miel<\/span><\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-4405-instructions\" class=\"wprm-recipe-instructions-container wprm-recipe-4405-instructions-container wprm-block-text-normal\" data-recipe=\"4405\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Instructions<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-4405-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\"><span style=\"display: block;\">M\u00e9langer farine, \u0153ufs, sucre, vanille, et 250 ml de lait dans un grand r\u00e9cipient.<\/span><\/div><\/li><li id=\"wprm-recipe-4405-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Battre avec un fouet manuel ou \u00e9lectrique jusqu'\u00e0 ce qu'il n,y ait plus de grumeaux.<\/div><\/li><li id=\"wprm-recipe-4405-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\"><span style=\"display: block;\">Ajouter les 500 ml de lait restant et bien m\u00e9langer de nouveau.<\/span><\/div><\/li><li id=\"wprm-recipe-4405-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Dans la po\u00eale o\u00f9 vous allez faire cuire les cr\u00eapes faire fondre le beurre \u00e0 feu tr\u00e8s doux. Cela va graisser votre po\u00eale en avance. Ensuite ajouter le beurre fondu dans la pate \u00e0 cr\u00eapes en remuant exactement au point de contact pour \u00e9viter que le beurre chaud ne cuise la pate. La dilution imm\u00e9diate en m\u00e9langeant \u00e9vite ce probl\u00e8me. En cas de doute laisser refroidir le beurre fondu quelques minutes sans qu'il se re-solidifie.<\/div><\/li><li id=\"wprm-recipe-4405-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Avec un papier sopalin\/serviette en papier, enlever l'exc\u00e8s de beurre de la po\u00eale tout en gardant une fine couche. Si vous souhaitez utiliser deux po\u00eales frottez la serviette en papier imbib\u00e9e du beurre sur la deuxi\u00e8me po\u00eale pour la pr\u00e9parer \u00e9galement.<\/div><\/li><li id=\"wprm-recipe-4405-step-0-5\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Faire chauffer la po\u00eale sur feu moyen. Chaque plaque chauffante ou cuisini\u00e8re \u00e0 gas est unique, il faut experimenter pour trouver l'intensit\u00e9 id\u00e9ale. En g\u00e9n\u00e9ral elle se trouve entre 50% et 75% de la puissance maximale. La pate \u00e0 cr\u00eapes doit commencer \u00e0 cuire imm\u00e9diatement apr\u00e8s \u00eatre vers\u00e9e. Si on entend \u00e0 peine le bruit de cuisson de la pate c'est que l'intensit\u00e9 n'est pas suffisante.<\/div><\/li><li id=\"wprm-recipe-4405-step-0-6\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Cuire le premier cot\u00e9 environ 1 minute. Vous savez que le premier cot\u00e9 est cuit quand vous ne voyez plus de liquide sur la pate. V\u00e9rifier avec une spatule plate la cuisson du premier c\u00f4t\u00e9. Il doit \u00eatre dor\u00e9 mais pas br\u00fbl\u00e9.<\/div><\/li><li id=\"wprm-recipe-4405-step-0-7\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Retourner la cr\u00eape d\u00e9licatement et cuire l'autre c\u00f4t\u00e9 une trentaine de secondes. R\u00e9p\u00e9ter l'operation pour les autres cr\u00eapes.<\/div><\/li><li id=\"wprm-recipe-4405-step-0-8\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Servir imm\u00e9diatement. On peut les conserver 2 \u00e0 3 jours au r\u00e9frig\u00e9rateur couvertes d'un film plastique pour \u00e9viter le s\u00e8chement.<\/div><\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-video\"><\/div><div id=\"wprm-recipe-video-container-4405\" class=\"wprm-recipe-video-container\"><h3 class=\"wprm-recipe-header wprm-recipe-video-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Vid\u00e9o<\/h3><div class=\"wprm-recipe-video\">\n<div class=\"adthrive-video-player in-post\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\" data-video-id=\"KbJCyAiL\" data-player-type=\"\" orientation=\"\" override-embed=\"\">\n\t\t\t<meta itemprop=\"uploadDate\" content=\"2017-04-12T18:46:01.000Z\" \/>\n\t\t<meta itemprop=\"name\" content=\"Comment faire les cr\u00eapes sucr\u00e9es\" \/>\n\t\t<meta itemprop=\"description\" content=\"Recette traditionnelle des cr\u00eapes sucr\u00e9es pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.\" \/>\n\t\t<meta itemprop=\"thumbnailUrl\" content=\"https:\/\/content.jwplatform.com\/thumbs\/KbJCyAiL-720.jpg\" \/>\n\t\t<meta itemprop=\"contentUrl\" content=\"https:\/\/content.jwplatform.com\/videos\/KbJCyAiL.mp4\" \/>\n\t<\/div>\n\n<amp-jwplayer data-media-id=\"KbJCyAiL\" data-player-id=\"6MBVYXNl\" layout=\"responsive\" width=\"16\" height=\"9\">\n<\/amp-jwplayer><\/div><\/div>\n\t\n\t\n<\/div><\/div><\/div>\n<p><a href=\"https:\/\/www.laylita.com\/recipes\/2017\/03\/04\/how-to-make-french-crepes\/\" target=\"_blank\" rel=\"noopener\">English version<\/a><\/p>\n<p>Les cr\u00eapes sont devenues une tradition du dimanche matin. Avec notre emploi du temps charg\u00e9 (par exemple amener les enfants faire du sport) on n&rsquo;a pas le temps tous les dimanches, mais on les fait assez souvent. Parfois juste pour nous. Parfois on invite des amis et leurs enfants. C&rsquo;est l\u00e0 qu&rsquo;il est pratique de pouvoir augmenter la vitesse de production de ces cr\u00eapes.<\/p>\n<h2>Les astuces de Nico pour faire des cr\u00eapes sucr\u00e9es parfaites<\/h2>\n<ul>\n<li>Utiliser une po\u00eale classique non collante. Pas besoin d&rsquo;une po\u00eale \u00e0 cr\u00eapes sp\u00e9cifique, mais il est important que la surface ne soit pas trop adh\u00e9sive.<\/li>\n<li>Pour une meilleure pate faites l\u00e0 quelques heures en avance. C&rsquo;est optionnel. Si vous la faites en avance m\u00e9langer la pate juste avant de commencer \u00e0 cuire car les ingr\u00e9dients peuvent s&rsquo;\u00eatre s\u00e9par\u00e9s.<\/li>\n<li>La premi\u00e8re cr\u00eape est souvent manqu\u00e9e du fait que la po\u00eale n&rsquo;est pas tout \u00e0 fait graiss\u00e9e et que vous \u00eates encore en train d&rsquo;ajuster la temp\u00e9rature. Ne vous d\u00e9couragez pas \u00e0 la premi\u00e8re, elle vous rend le travail plus efficace pour les suivantes.<\/li>\n<li>Quand vous sortez les cr\u00eapes cuites de chaque c\u00f4t\u00e9 et les mettez dans une assiette elles peuvent para\u00eetre s\u00e8ches. En les empilant l&rsquo;humidit\u00e9 se propage entre chacune et les rend plus souples.<\/li>\n<li>Vous pouvez pr\u00e9parer votre selection de garnitures: sucre, confiture, caramel, nutella. Les fruits frais coup\u00e9s en lamelle comme la banane, la fraise, ou les framboises, font de bonnes options nutritives et naturelles.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11344 size-full\" title=\"Les cr\u00eapes sont simples \u00e0 r\u00e9ussir avec la bonne m\u00e9thode et les ustensiles appropri\u00e9s.\" src=\"https:\/\/www.laylita.com\/recipes\/wp-content\/uploads\/2017\/02\/Crepes-recipe.jpg\" alt=\"Les cr\u00eapes sont simples \u00e0 r\u00e9ussir avec la bonne m\u00e9thode et les ustensiles appropri\u00e9s.\" width=\"640\" height=\"427\"><\/p>\n<h2>Photos \u00e9tape par \u00e9tape, comment faire des cr\u00eapes sucr\u00e9es:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11348 size-full\" title=\"Ingr\u00e9dients et recette de base pour la pate \u00e0 cr\u00eapes\" src=\"https:\/\/www.laylita.com\/recipes\/wp-content\/uploads\/2017\/02\/Preparation-for-French-style-crepes.jpg\" alt=\"Ingr\u00e9dients et recette de base pour la pate \u00e0 cr\u00eapes\" width=\"640\" height=\"2200\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11350 size-full\" title=\"Id\u00e9es de garnitures pour les cr\u00eapes\" src=\"https:\/\/www.laylita.com\/recipes\/wp-content\/uploads\/2017\/02\/Sweet-crepes-topping-ideas.jpg\" alt=\"Id\u00e9es de garnitures pour les cr\u00eapes\" width=\"640\" height=\"960\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-11347 size-full\" title=\"Comment faire les cr\u00eapes maison: suggestion de pr\u00e9sentation\" src=\"https:\/\/www.laylita.com\/recipes\/wp-content\/uploads\/2017\/02\/How-to-make-sweet-crepes.jpg\" alt=\"Comment faire les cr\u00eapes maison: suggestion de pr\u00e9sentation\" width=\"640\" height=\"427\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Recette traditionnelle des cr\u00eapes sucr\u00e9es pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.<\/p>\n","protected":false},"author":2,"featured_media":3463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2721,5,16,12,150,2902,20,6,10,157,332],"tags":[],"class_list":["post-3457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brunch","category-cuisine-de-base","category-cuisine-francaise","category-desserts","category-fete-des-meres","category-gouter","category-menu-enfants","category-petit-dejeuner","category-reconfortant","category-saint-valentin","category-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment faire les cr\u00eapes sucr\u00e9es &#8211; Recettes de Laylita<\/title>\n<meta name=\"description\" content=\"Recette traditionnelle des cr\u00eapes sucr\u00e9es fran\u00e7aises pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment faire les cr\u00eapes sucr\u00e9es &#8211; Recettes de Laylita\" \/>\n<meta property=\"og:description\" content=\"Recette traditionnelle des cr\u00eapes sucr\u00e9es fran\u00e7aises pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/\" \/>\n<meta property=\"og:site_name\" content=\"Recettes de Laylita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RecettesdeLaylita\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/RecettesdeLaylita\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-11T20:32:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T14:43:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Recettes de Laylita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@laylita\" \/>\n<meta name=\"twitter:site\" content=\"@laylita\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Recettes de Laylita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/\"},\"author\":{\"name\":\"Recettes de Laylita\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#\\\/schema\\\/person\\\/a95757de7530e685eb4b97e3281098dc\"},\"headline\":\"Comment faire les cr\u00eapes sucr\u00e9es\",\"datePublished\":\"2017-04-11T20:32:56+00:00\",\"dateModified\":\"2026-01-13T14:43:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/\"},\"wordCount\":1011,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/faire-crepes-sucrees.jpg\",\"articleSection\":[\"Brunch\",\"Cuisine de base\",\"Cuisine Fran\u00e7aise\",\"Desserts\",\"F\u00eate des m\u00e8res\",\"Go\u00fbter\",\"Menu enfants\",\"Petit d\u00e9jeuner\",\"R\u00e9confortant\",\"Saint Valentin\",\"Vid\u00e9o\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/\",\"name\":\"Comment faire les cr\u00eapes sucr\u00e9es &#8211; Recettes de Laylita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/faire-crepes-sucrees.jpg\",\"datePublished\":\"2017-04-11T20:32:56+00:00\",\"dateModified\":\"2026-01-13T14:43:37+00:00\",\"description\":\"Recette traditionnelle des cr\u00eapes sucr\u00e9es fran\u00e7aises pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/faire-crepes-sucrees.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/faire-crepes-sucrees.jpg\",\"width\":800,\"height\":533,\"caption\":\"P\u00e2te \u00e0 cr\u00eapes sucr\u00e9es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/comment-faire-crepes-sucrees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toutes les recettes\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/categorie\\\/toutes-les-recettes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Par plat\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/categorie\\\/toutes-les-recettes\\\/par-plat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Petit d\u00e9jeuner\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/categorie\\\/toutes-les-recettes\\\/par-plat\\\/petit-dejeuner\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Comment faire les cr\u00eapes sucr\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#website\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/\",\"name\":\"Recettes de Laylita\",\"description\":\"Cuisine fran\u00e7aise et sud-Am\u00e9ricaine illustr\u00e9e de photos et vid\u00e9os.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#organization\",\"name\":\"Laylita.com\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Laylita-640px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/wp-content\\\/uploads\\\/2016\\\/12\\\/Laylita-640px.jpg\",\"width\":640,\"height\":301,\"caption\":\"Laylita.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RecettesdeLaylita\",\"https:\\\/\\\/x.com\\\/laylita\",\"https:\\\/\\\/instagram.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvNX-qrEsv2vNNzG2KXSRag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/#\\\/schema\\\/person\\\/a95757de7530e685eb4b97e3281098dc\",\"name\":\"Recettes de Laylita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77e24ba43d11ce2f24b45959808c7e56bf43a3a2b9d238d863e53178b3c6ebbb?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77e24ba43d11ce2f24b45959808c7e56bf43a3a2b9d238d863e53178b3c6ebbb?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/77e24ba43d11ce2f24b45959808c7e56bf43a3a2b9d238d863e53178b3c6ebbb?s=96&d=mm&r=pg\",\"caption\":\"Recettes de Laylita\"},\"description\":\"Recettes\",\"sameAs\":[\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/\",\"https:\\\/\\\/www.facebook.com\\\/RecettesdeLaylita\\\/\",\"https:\\\/\\\/x.com\\\/laylita\"],\"url\":\"https:\\\/\\\/www.laylita.com\\\/recettes\\\/author\\\/recettes-de-laylita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment faire les cr\u00eapes sucr\u00e9es &#8211; Recettes de Laylita","description":"Recette traditionnelle des cr\u00eapes sucr\u00e9es fran\u00e7aises pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment faire les cr\u00eapes sucr\u00e9es &#8211; Recettes de Laylita","og_description":"Recette traditionnelle des cr\u00eapes sucr\u00e9es fran\u00e7aises pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.","og_url":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/","og_site_name":"Recettes de Laylita","article_publisher":"https:\/\/www.facebook.com\/RecettesdeLaylita","article_author":"https:\/\/www.facebook.com\/RecettesdeLaylita\/","article_published_time":"2017-04-11T20:32:56+00:00","article_modified_time":"2026-01-13T14:43:37+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","type":"image\/jpeg"}],"author":"Recettes de Laylita","twitter_card":"summary_large_image","twitter_creator":"@laylita","twitter_site":"@laylita","twitter_misc":{"\u00c9crit par":"Recettes de Laylita","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#article","isPartOf":{"@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/"},"author":{"name":"Recettes de Laylita","@id":"https:\/\/www.laylita.com\/recettes\/#\/schema\/person\/a95757de7530e685eb4b97e3281098dc"},"headline":"Comment faire les cr\u00eapes sucr\u00e9es","datePublished":"2017-04-11T20:32:56+00:00","dateModified":"2026-01-13T14:43:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/"},"wordCount":1011,"commentCount":0,"publisher":{"@id":"https:\/\/www.laylita.com\/recettes\/#organization"},"image":{"@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","articleSection":["Brunch","Cuisine de base","Cuisine Fran\u00e7aise","Desserts","F\u00eate des m\u00e8res","Go\u00fbter","Menu enfants","Petit d\u00e9jeuner","R\u00e9confortant","Saint Valentin","Vid\u00e9o"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/","url":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/","name":"Comment faire les cr\u00eapes sucr\u00e9es &#8211; Recettes de Laylita","isPartOf":{"@id":"https:\/\/www.laylita.com\/recettes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#primaryimage"},"image":{"@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","datePublished":"2017-04-11T20:32:56+00:00","dateModified":"2026-01-13T14:43:37+00:00","description":"Recette traditionnelle des cr\u00eapes sucr\u00e9es fran\u00e7aises pr\u00e9par\u00e9es avec farine, \u0153ufs, lait, extrait de vanille et beurre fondu pour la p\u00e2te, plus d\u00e9corations.","breadcrumb":{"@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#primaryimage","url":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","contentUrl":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","width":800,"height":533,"caption":"P\u00e2te \u00e0 cr\u00eapes sucr\u00e9es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laylita.com\/recettes\/comment-faire-crepes-sucrees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.laylita.com\/recettes\/"},{"@type":"ListItem","position":2,"name":"Toutes les recettes","item":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/"},{"@type":"ListItem","position":3,"name":"Par plat","item":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/par-plat\/"},{"@type":"ListItem","position":4,"name":"Petit d\u00e9jeuner","item":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/par-plat\/petit-dejeuner\/"},{"@type":"ListItem","position":5,"name":"Comment faire les cr\u00eapes sucr\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.laylita.com\/recettes\/#website","url":"https:\/\/www.laylita.com\/recettes\/","name":"Recettes de Laylita","description":"Cuisine fran\u00e7aise et sud-Am\u00e9ricaine illustr\u00e9e de photos et vid\u00e9os.","publisher":{"@id":"https:\/\/www.laylita.com\/recettes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laylita.com\/recettes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.laylita.com\/recettes\/#organization","name":"Laylita.com","url":"https:\/\/www.laylita.com\/recettes\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.laylita.com\/recettes\/#\/schema\/logo\/image\/","url":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2016\/12\/Laylita-640px.jpg","contentUrl":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2016\/12\/Laylita-640px.jpg","width":640,"height":301,"caption":"Laylita.com"},"image":{"@id":"https:\/\/www.laylita.com\/recettes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RecettesdeLaylita","https:\/\/x.com\/laylita","https:\/\/instagram.com\/laylapujol\/","https:\/\/www.pinterest.com\/laylapujol\/","https:\/\/www.youtube.com\/channel\/UCvNX-qrEsv2vNNzG2KXSRag"]},{"@type":"Person","@id":"https:\/\/www.laylita.com\/recettes\/#\/schema\/person\/a95757de7530e685eb4b97e3281098dc","name":"Recettes de Laylita","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/77e24ba43d11ce2f24b45959808c7e56bf43a3a2b9d238d863e53178b3c6ebbb?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/77e24ba43d11ce2f24b45959808c7e56bf43a3a2b9d238d863e53178b3c6ebbb?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/77e24ba43d11ce2f24b45959808c7e56bf43a3a2b9d238d863e53178b3c6ebbb?s=96&d=mm&r=pg","caption":"Recettes de Laylita"},"description":"Recettes","sameAs":["https:\/\/www.laylita.com\/recettes\/","https:\/\/www.facebook.com\/RecettesdeLaylita\/","https:\/\/x.com\/laylita"],"url":"https:\/\/www.laylita.com\/recettes\/author\/recettes-de-laylita\/"}]}},"featured_image_src":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","featured_image_src_square":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","author_info":{"display_name":"Recettes de Laylita","author_link":"https:\/\/www.laylita.com\/recettes\/author\/recettes-de-laylita\/"},"jetpack_featured_media_url":"https:\/\/www.laylita.com\/recettes\/wp-content\/uploads\/2017\/04\/faire-crepes-sucrees.jpg","jetpack_shortlink":"https:\/\/wp.me\/pLFEY-TL","jetpack-related-posts":[{"id":1684,"url":"https:\/\/www.laylita.com\/recettes\/comment-faire-pate-tarte-sucree\/","url_meta":{"origin":3457,"position":0},"title":"Comment faire une p\u00e2te \u00e0 tarte sucr\u00e9e","author":"Recettes de Laylita","date":"03\/09\/2015","format":false,"excerpt":"Comment faire une p\u00e2te \u00e0 tarte sucr\u00e9e: recette facile pour les pates \u00e0 tartes sucr\u00e9es, pates \u00e0 gateaux, avec photos et instructions \u00e9tape par \u00e9tape.","rel":"","context":"Dans &quot;Cuisine d'Europe&quot;","block_context":{"text":"Cuisine d'Europe","link":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/par-region\/cuisine-europe\/"},"img":{"alt_text":"Comment faire une p\u00e2te \u00e0 tarte sucr\u00e9e","src":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/11\/Sweet-tart-dough-recipe.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/11\/Sweet-tart-dough-recipe.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/11\/Sweet-tart-dough-recipe.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2289,"url":"https:\/\/www.laylita.com\/recettes\/preparer-la-pate-pour-empanadas-sucrees\/","url_meta":{"origin":3457,"position":1},"title":"Comment pr\u00e9parer la p\u00e2te pour empanadas sucr\u00e9es","author":"Recettes de Laylita","date":"30\/05\/2016","format":false,"excerpt":"Recette facile pour pr\u00e9parer la pate d'empanadas sucr\u00e9es, douces pour desserts, ou comment faire une pate \u00e0 tarte sucr\u00e9e en utilisant un robot mixeur.","rel":"","context":"Dans &quot;Cuisine d'Am\u00e9rique Centrale&quot;","block_context":{"text":"Cuisine d'Am\u00e9rique Centrale","link":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/par-region\/cuisine-amerique-centrale\/"},"img":{"alt_text":"Comment pr\u00e9parer la p\u00e2te pour empanadas sucr\u00e9es","src":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2016\/05\/Comment-pr%C3%A9parer-la-p%C3%A2te-pour-empanadas-sucr%C3%A9es.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2016\/05\/Comment-pr%C3%A9parer-la-p%C3%A2te-pour-empanadas-sucr%C3%A9es.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2016\/05\/Comment-pr%C3%A9parer-la-p%C3%A2te-pour-empanadas-sucr%C3%A9es.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1784,"url":"https:\/\/www.laylita.com\/recettes\/empanadas-pain-epices-poires\/","url_meta":{"origin":3457,"position":2},"title":"Empanadas au pain d\u2019\u00e9pices avec garniture de poire","author":"Recettes de Laylita","date":"10\/11\/2015","format":false,"excerpt":"Ces d\u00e9licieuses empanadas aux poires sont le fruit de ma derni\u00e8re exp\u00e9rimentation d\u2019empanadas et sont rapidement devenues mes empanadas sucr\u00e9es les plus demand\u00e9es en dessert.","rel":"","context":"Dans &quot;Cannelle&quot;","block_context":{"text":"Cannelle","link":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/par-ingredient\/epices\/cannelle\/"},"img":{"alt_text":"Empanadas aux poires","src":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/11\/Pear-empanadas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/11\/Pear-empanadas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/11\/Pear-empanadas.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":7967,"url":"https:\/\/www.laylita.com\/recettes\/empanadas-aux-pommes-et-a-la-cannelle-chaussons\/","url_meta":{"origin":3457,"position":3},"title":"Empanadas aux pommes et \u00e0 la cannelle (Chaussons aux pommes)","author":"Layla Pujol","date":"18\/01\/2026","format":false,"excerpt":"Empanadas aux pommes avec une p\u00e2te \u00e0 la cannelle fait-maison. Ces empanadas sont cuits au four et recouverts de sucre \u00e0 la cannelle.","rel":"","context":"Dans &quot;Automne&quot;","block_context":{"text":"Automne","link":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/saison\/automne\/"},"img":{"alt_text":"Empanadas aux pommes et \u00e0 la cannelle sur une assiette blanche, servies avec une sauce caramel au dulce de leche","src":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2026\/01\/Recette-facile-dempanadas-aux-pommes-et-a-la-cannelle.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2026\/01\/Recette-facile-dempanadas-aux-pommes-et-a-la-cannelle.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2026\/01\/Recette-facile-dempanadas-aux-pommes-et-a-la-cannelle.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2026\/01\/Recette-facile-dempanadas-aux-pommes-et-a-la-cannelle.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2026\/01\/Recette-facile-dempanadas-aux-pommes-et-a-la-cannelle.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":685,"url":"https:\/\/www.laylita.com\/recettes\/preparer-la-pate-empanadas\/","url_meta":{"origin":3457,"position":4},"title":"Comment pr\u00e9parer la p\u00e2te pour empanadas \u00e0 cuire au four","author":"Recettes de Laylita","date":"13\/07\/2014","format":false,"excerpt":"Les empanadas sont des chaussons fourr\u00e9s espagnols ou sud Am\u00e9ricains sucr\u00e9s ou sal\u00e9s. Cette pr\u00e9paration est pour la pate empanadas pour cuisson au four.","rel":"","context":"Dans &quot;Cuisine d'Am\u00e9rique du Sud&quot;","block_context":{"text":"Cuisine d'Am\u00e9rique du Sud","link":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/par-region\/cuisine-amerique-du-sud\/"},"img":{"alt_text":"Comment pr\u00e9parer la p\u00e2te pour empanadas \u00e0 cuire au four","src":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/07\/Pr%C3%A9paration-pate-empanada.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/07\/Pr%C3%A9paration-pate-empanada.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/07\/Pr%C3%A9paration-pate-empanada.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2014\/07\/Pr%C3%A9paration-pate-empanada.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":408,"url":"https:\/\/www.laylita.com\/recettes\/guaguas-de-pan-ou-brioches-figurines-de-pain\/","url_meta":{"origin":3457,"position":5},"title":"Guaguas de pan ou brioches figurines de pain","author":"Recettes de Laylita","date":"17\/10\/2012","format":false,"excerpt":"Les brioches guaguas de pan sont des figurines de pain traditionnelles en Equateur, en forme de b\u00e9b\u00e9s ou poup\u00e9es, d\u00e9licieuses et icones et certaines f\u00eates.","rel":"","context":"Dans &quot;Cuisine d'Am\u00e9rique du Sud&quot;","block_context":{"text":"Cuisine d'Am\u00e9rique du Sud","link":"https:\/\/www.laylita.com\/recettes\/categorie\/toutes-les-recettes\/par-region\/cuisine-amerique-du-sud\/"},"img":{"alt_text":"Guaguas Equateur","src":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2012\/10\/Guaguas-de-pan-ou-brioches-figurines-de-pain.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2012\/10\/Guaguas-de-pan-ou-brioches-figurines-de-pain.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recettes\/wp-content\/uploads\/2012\/10\/Guaguas-de-pan-ou-brioches-figurines-de-pain.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/posts\/3457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/comments?post=3457"}],"version-history":[{"count":21,"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/posts\/3457\/revisions"}],"predecessor-version":[{"id":4408,"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/posts\/3457\/revisions\/4408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/media\/3463"}],"wp:attachment":[{"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/media?parent=3457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/categories?post=3457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laylita.com\/recettes\/wp-json\/wp\/v2\/tags?post=3457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}