{"id":4093,"date":"2014-03-29T07:46:14","date_gmt":"2014-03-29T14:46:14","guid":{"rendered":"https:\/\/www.laylita.com\/recetas\/?p=4093"},"modified":"2020-01-16T16:14:19","modified_gmt":"2020-01-16T21:14:19","slug":"sanduchitos-de-hornado-de-chancho-con-aguacate","status":"publish","type":"post","link":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/","title":{"rendered":"Sanduchitos de hornado de chancho con aguacate"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Estos sanduchitos de hornado de chancho o pernil de cerdo se preparan con aguacate, cebollas encurtidas, y aj\u00ed criollo o salsa picante de cilantro.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\" alt=\"Sanduchitos de hornado de chancho con aguacate\"\/><\/figure>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.laylita.com\/recipes\/roast-pork-sliders\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"English version (opens in a new tab)\">English version<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada vez que preparamos <span style=\"color: #0000ff;\"><a title=\"Receta del hornado de chancho\" rel=\"noopener noreferrer\" href=\"https:\/\/www.laylita.com\/recetas\/2012\/11\/09\/chancho-o-cerdo-hornado-receta-facil\/\" target=\"_blank\"><span style=\"color: #0000ff;\">hornado de chancho<\/span><\/a><\/span> o cerdo al horno, nos quedan algunas sobras. Las sobras del hornado se pueden usar para preparar una variedad de platillos. En esta ocasi\u00f3n decid\u00ed preparar unos sanduchitos para mis hijos cuando llegaron de la escuela. Estaba pensando en prepararles unas quesadillas (estilo mexicano), o empanadas, pero tambi\u00e9n ten\u00eda unos cuantos pancitos peque\u00f1os que necesitaba usar. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-o-pernil.jpg\" alt=\"Sanduchitos de hornado o pernil\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n ten\u00eda aguacates maduros y casi siempre tenemos cebollas encurtidas. A mis hijos les encanta lo picante as\u00ed que tambi\u00e9n le agregue un poquito de aj\u00ed criollo, una salsa picante de aj\u00edes o chiles con cilantro. La combinaci\u00f3n de la carne de cerdo o chancho hornado, el aguacate, las cebollas encurtidas, y el aj\u00ed en un solo bocadito de sanduche es una delicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos deliciosos sanduchitos de hornado de chancho con crema de aguacate son un excelente snack o bocadito para ni\u00f1os con hambre (o esposos con hambre). Tambi\u00e9n se pueden servir como aperitivos o entradas para una fiesta. Suelo guardar un poco de hornado o pernil en la congeladora y luego lo uso para preparar estos sanduchitos \u2013 y tambi\u00e9n para relleno de empanadas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Como-preparar-sanduches-de-pernil-o-hornado.jpg\" alt=\"Como preparar sanduches de pernil o hornado\"\/><\/figure>\n\n\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-9998\" class=\"wprm-recipe-container\" data-recipe-id=\"9998\" data-servings=\"6\"><div class=\"wprm-recipe wprm-recipe-template-cutout-v2\"><div class=\"wprm-recipe-image wprm-block-image-rounded\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 10px;border-style: solid;border-color: #ffffff;border-radius: 30px;\" width=\"200\" height=\"133\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\" class=\"attachment-200x200 size-200x200\" alt=\"Sanduchitos de hornado de chancho con aguacate\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate-640x426.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate-600x400.jpg 600w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate-180x120.jpg 180w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" data-attachment-id=\"4100\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/sanduchitos-de-hornado-de-chancho-con-aguacate-2\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-title=\"Sanduchitos de hornado de chancho con aguacate\" data-image-description=\"&lt;p&gt;Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\" \/><\/div>\n<div class=\"wprm-recipe-template-cutout-v2-container\">\n\t<div class=\"wprm-recipe-template-cutout-v2-header\">\n\t\t<h2 class=\"wprm-recipe-name wprm-block-text-bold\">Sanduchitos de hornado de chancho con aguacate<\/h2>\n\t\t<div class=\"wprm-spacer\" style=\"height: 5px;\"><\/div>\n\t\t<div class=\"wprm-recipe-summary wprm-block-text-normal\">Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.<\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<style>#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-full svg * { fill: #f8e71c; }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-33 svg * { fill: url(#wprm-recipe-user-rating-0-33); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-50 svg * { fill: url(#wprm-recipe-user-rating-0-50); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-66 svg * { fill: url(#wprm-recipe-user-rating-0-66); }linearGradient#wprm-recipe-user-rating-0-33 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-50 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-66 stop { stop-color: #f8e71c; }<\/style><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"0\" height=\"0\" style=\"display:block;width:0px;height:0px\"><defs><linearGradient id=\"wprm-recipe-user-rating-0-33\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-50\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-66\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><\/svg><div id=\"wprm-recipe-user-rating-0\" class=\"wprm-recipe-rating wprm-recipe-rating-recipe-9998 wprm-user-rating wprm-recipe-rating-separate wprm-user-rating-not-voted wprm-user-rating-allowed\" data-recipe=\"9998\" data-average=\"4.94\" data-count=\"15\" data-total=\"74\" data-user=\"0\" data-decimals=\"2\"data-modal-uid=\"user-rating\"><span class=\"wprm-rating-star wprm-rating-star-1 wprm-rating-star-full\" data-rating=\"1\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 1 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-2 wprm-rating-star-full\" data-rating=\"2\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 2 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-3 wprm-rating-star-full\" data-rating=\"3\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 3 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-4 wprm-rating-star-full\" data-rating=\"4\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 4 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-5 wprm-rating-star-full\" data-rating=\"5\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 5 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><div class=\"wprm-recipe-rating-details wprm-block-text-normal\"><span class=\"wprm-recipe-rating-average\">4.94<\/span> de <span class=\"wprm-recipe-rating-count\">15<\/span> votos<\/div><\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<a href=\"https:\/\/www.laylita.com\/recetas\/wprm_print\/sanduchitos-de-hornado-de-chancho-con-aguacate\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal wprm-recipe-print-inline-button wprm-recipe-link-inline-button wprm-color-accent\" data-recipe-id=\"9998\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Imprimir<\/a>\n\t\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.laylita.com%2Frecetas%2Fsanduchitos-de-hornado-de-chancho-con-aguacate%2F&amp;media=https%3A%2F%2Fwww.laylita.com%2Frecetas%2Fwp-content%2Fuploads%2FSanduchitos-de-hornado-de-chancho-con-aguacate.jpg&amp;description=Sanduchitos+de+hornado+de+chancho+o+pernil+de+cerdo+preparados+con+aguacate%2C+cebollas+encurtidas%2C+y+aji+criollo+o+salsa+picante+de+cilantro.&amp;is_video=false\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"9998\" data-url=\"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/\" data-media=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\" data-description=\"Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.\" data-repin=\"\" role=\"button\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal wprm-recipe-pin-inline-button wprm-recipe-link-inline-button wprm-color-accent\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\t<a href=\"#commentform\" class=\"wprm-recipe-jump-to-comments wprm-recipe-link wprm-block-text-normal wprm-recipe-jump-to-comments-inline-button wprm-recipe-link-inline-button wprm-color-accent\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\"><span class=\"wprm-recipe-icon wprm-recipe-jump-to-comments-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 16 16\" xml:space=\"preserve\" width=\"16\" height=\"16\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><polygon data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" points=\" 13,0.5 15.5,3 7.5,11 4,12 5,8.5 \"><\/polygon> <line data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" x1=\"11\" y1=\"2.5\" x2=\"13.5\" y2=\"5\"><\/line> <path fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" d=\"M13.5,9.5v5 c0,0.552-0.448,1-1,1h-11c-0.552,0-1-0.448-1-1v-11c0-0.552,0.448-1,1-1h5\"><\/path> <\/g><\/svg><\/span> Preguntas o comentarios<\/a>\n\t\t<div class=\"wprm-spacer\"><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-tags-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-course-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-course-label\">Plato: <\/span><span class=\"wprm-recipe-course wprm-block-text-normal\">Aperitivo, Entrada, Para picar<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-cuisine-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-cuisine-label\">Cocina: <\/span><span class=\"wprm-recipe-cuisine wprm-block-text-normal\">Ecuatoriana, Fusi\u00f3n, Latina<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-keyword-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-keyword-label\">Palabra clave: <\/span><span class=\"wprm-recipe-keyword wprm-block-text-normal\">Aguacate, Cebollas encurtidas, Hornado de chancho, S\u00e1nduche, Sanduche de chancho con aguacate, Sanduchito, Sliders<\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-times-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-prep-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-prep-time-label\">Tiempo de preparaci\u00f3n: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">10<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-total-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-total-time-label\">Tiempo Total: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-total_time wprm-recipe-total_time-minutes\">10<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-total_time-unit wprm-recipe-total_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-servings-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-servings-label\">Rinde: <\/span><span class=\"wprm-recipe-servings-with-unit\"><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-9998 wprm-recipe-servings-adjustable-tooltip wprm-block-text-normal\" data-recipe=\"9998\" aria-label=\"Adjust recipe servings\">6<\/span> <span class=\"wprm-recipe-servings-unit wprm-recipe-details-unit wprm-block-text-normal\">sanduches peque\u00f1os<\/span><\/span><\/div>\n\t\t\n\t\t\n\t<\/div>\n\t<div id=\"recipe-9998-ingredients\" class=\"wprm-recipe-ingredients-container wprm-recipe-ingredients-no-images wprm-recipe-9998-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"9998\" data-servings=\"6\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredientes<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">taza<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\"><a href=\"https:\/\/www.laylita.com\/recetas\/chancho-o-cerdo-hornado-receta-facil\/\" class=\"wprm-recipe-ingredient-link\" target=\"_blank\">carne de chancho o cerdo hornado<\/a><\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">desmenuzado<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">6<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">panes peque\u00f1os<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">aguacates maduros<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">pelados y sin pepa<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">cucharada de jugo de lim\u00f3n<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Sal al gusto<\/span><\/li><\/ul><\/div><div class=\"wprm-recipe-ingredient-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-ingredient-group-name wprm-block-text-bold\">Para servir:<\/h4><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\"><a href=\"https:\/\/www.laylita.com\/recetas\/cebollas-encurtidas-receta\/\" class=\"wprm-recipe-ingredient-link\" target=\"_blank\">Cebollas encurtidas al gusto<\/a><\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\"><a href=\"https:\/\/www.laylita.com\/recetas\/aji-criollo\/\" class=\"wprm-recipe-ingredient-link\" target=\"_blank\">Aji criollo al gusto<\/a><\/span><\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-9998-instructions\" class=\"wprm-recipe-instructions-container wprm-recipe-9998-instructions-container wprm-block-text-normal\" data-recipe=\"9998\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Preparaci\u00f3n<\/h3><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-9998-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Para preparar la crema de aguacate, aplaste los aguacates con el jugo de lim\u00f3n y sal al gusto hasta tener un pur\u00e9 o crema.<\/div><\/li><li id=\"wprm-recipe-9998-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Corte los panes por la mitad y unte cada mitad generosamente con la crema de aguacate.<\/div><\/li><li id=\"wprm-recipe-9998-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Agregue una capa de la carne desmenuzada de chancho o cerdo al sanduche. Agregue un poco de cebollas encurtidas y aji criollo encima de la carne.<\/div><\/li><li id=\"wprm-recipe-9998-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Sirva inmediatamente.<\/div><\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-video\"><\/div>\n\t\n\t\n<\/div><\/div><\/div>\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.laylita.com\/recetas\/2012\/11\/09\/chancho-o-cerdo-hornado-receta-facil\/\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" data-attachment-id=\"2305\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/chancho-o-cerdo-hornado-receta-facil\/hornado-ecuatoriano-o-cerdo-asado\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado.jpg\" data-orig-size=\"640,427\" data-comments-opened=\"1\" data-image-title=\"Hornado de chancho o cerdo asado\" data-image-description=\"&lt;p&gt;El hornado de chancho o cerdo es un plato tradicional Ecuatoriano de chancho asado al horno en un adobo de cerveza o chicha, ajo, comino, y achiote.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado.jpg\" alt=\"Hornado ecuatoriano\" class=\"wp-image-2305\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado-600x400.jpg 600w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado-180x120.jpg 180w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recetas adicionales:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Receta del <span style=\"color: #0000ff;\"><a title=\"Receta facil para hornado o pernil\" href=\"https:\/\/www.laylita.com\/recetas\/2012\/11\/09\/chancho-o-cerdo-hornado-receta-facil\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #0000ff;\">hornado de chancho<\/span><\/a><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Receta del <span style=\"color: #0000ff;\"><a title=\"Pernil lojano\" href=\"https:\/\/www.laylita.com\/recetas\/2008\/03\/18\/pernil-lojano\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #0000ff;\">pernil lojano<\/span><\/a><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Receta de las <span style=\"color: #0000ff;\"><a title=\"Cebollas encurtidas\" href=\"https:\/\/www.laylita.com\/recetas\/2011\/12\/20\/cebollas-encurtidas-receta\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #0000ff;\">cebollas encurtidas<\/span><\/a><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Receta del <span style=\"color: #0000ff;\"><a title=\"Receta del aji criollo\" href=\"https:\/\/www.laylita.com\/recetas\/2008\/03\/05\/aji-criollo\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #0000ff;\">aji criollo&nbsp;<\/span><\/a><\/span><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-con-cerdo-o-chancho-y-aguacate.jpg\" alt=\"Sanduches con cerdo o chancho y aguacate\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"428\" data-attachment-id=\"4099\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/sanduches-faciles-de-preparar\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-faciles-de-preparar.jpg\" data-orig-size=\"640,428\" data-comments-opened=\"1\" data-image-title=\"Sanduches faciles de preparar\" data-image-description=\"&lt;p&gt;Sanduches con cerdo o chancho y aguacate&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-faciles-de-preparar.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-faciles-de-preparar.jpg\" alt=\"Sanduches faciles de preparar\" class=\"wp-image-4099\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-faciles-de-preparar.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-faciles-de-preparar-600x400.jpg 600w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-faciles-de-preparar-180x120.jpg 180w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" data-attachment-id=\"4098\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/sanduches-de-pernil\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-de-pernil.jpg\" data-orig-size=\"640,800\" data-comments-opened=\"1\" data-image-title=\"Sanduches de pernil\" data-image-description=\"&lt;p&gt;Sanduchitos de hornado o pernil&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-de-pernil.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-de-pernil.jpg\" alt=\"Sanduches de pernil o hornado\" class=\"wp-image-4098\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-de-pernil.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-de-pernil-512x640.jpg 512w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduches-de-pernil-260x324.jpg 260w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-size: 14px; line-height: 1.5em;\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.<\/p>\n","protected":false},"author":19,"featured_media":4100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[187,7,472,493,20,183,439,14,26,390,530,521,12],"tags":[],"class_list":["post-4093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bocaditos","category-carne","category-cerdo-o-chancho","category-ecuador","category-entrada","category-faciles","category-latinohispano","category-norteamerica","category-para-ninos","category-aguacates","category-sobras-restos","category-sanduches","category-sudamerica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sanduchitos de hornado de chancho o pernil de cerdo con aguacate<\/title>\n<meta name=\"description\" content=\"Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanduchitos de hornado de chancho o pernil de cerdo con aguacate\" \/>\n<meta property=\"og:description\" content=\"Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/\" \/>\n<meta property=\"og:site_name\" content=\"Laylita.com \u2013 Recetas de Cocina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LaylitaCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/LaylitaCom\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-29T14:46:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-16T21:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Layla Pujol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@laylita\" \/>\n<meta name=\"twitter:site\" content=\"@LaylaPujol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Layla Pujol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/\"},\"author\":{\"name\":\"Layla Pujol\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/person\\\/bb152c0e2cdff3c7b7ab8d516cd8f161\"},\"headline\":\"Sanduchitos de hornado de chancho con aguacate\",\"datePublished\":\"2014-03-29T14:46:14+00:00\",\"dateModified\":\"2020-01-16T21:14:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/\"},\"wordCount\":388,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\",\"articleSection\":[\"Bocaditos y snacks\",\"Carne\",\"Cerdo, chancho o puerco\",\"Ecuador\",\"Entradas y Aperitivos\",\"F\u00e1ciles\",\"Latino\\\/Hispano\",\"Norteamerica\",\"Para ni\u00f1os\",\"Recetas con aguacate o palta\",\"Recetas con sobras y restos de comida\",\"Sanduches\",\"Sudamerica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/\",\"name\":\"Sanduchitos de hornado de chancho o pernil de cerdo con aguacate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\",\"datePublished\":\"2014-03-29T14:46:14+00:00\",\"dateModified\":\"2020-01-16T21:14:19+00:00\",\"description\":\"Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg\",\"width\":800,\"height\":533,\"caption\":\"Sanduchitos de hornado de chancho con aguacate\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/sanduchitos-de-hornado-de-chancho-con-aguacate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todas las recetas\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Por plato\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/plato\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bocaditos y snacks\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/plato\\\/bocaditos\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Sanduchitos de hornado de chancho con aguacate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#website\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\",\"name\":\"Laylita.com \u2013 Recetas de Cocina\",\"description\":\"Encuentra recetas deliciosas y f\u00e1ciles de cocina casera ecuatoriana, latina, e internacional en espa\u00f1ol - con videos y fotos paso a paso.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\",\"name\":\"Laylita.com\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Laylita.com-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Laylita.com-logo.jpg\",\"width\":559,\"height\":558,\"caption\":\"Laylita.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LaylitaCom\",\"https:\\\/\\\/x.com\\\/LaylaPujol\",\"https:\\\/\\\/instagram.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvNX-qrEsv2vNNzG2KXSRag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/person\\\/bb152c0e2cdff3c7b7ab8d516cd8f161\",\"name\":\"Layla Pujol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"caption\":\"Layla Pujol\"},\"description\":\"Mi nombre es Layla Pujol, tambi\u00e9n conocida como Laylita, y soy ecuatoriana, aunque actualmente vivo en Europa. Muchas de mis recetas son inspiradas por la comida ecuatoriana, por la cocina americana-mexicana de mi mam\u00e1, quien creci\u00f3 en Nuevo M\u00e9xico, y tambi\u00e9n por la cocina de mi abuelita en Texas.\",\"sameAs\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/quien-es-laylita\\\/\",\"https:\\\/\\\/www.facebook.com\\\/LaylitaCom\",\"https:\\\/\\\/x.com\\\/laylita\"],\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/author\\\/laylita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sanduchitos de hornado de chancho o pernil de cerdo con aguacate","description":"Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/","og_locale":"es_ES","og_type":"article","og_title":"Sanduchitos de hornado de chancho o pernil de cerdo con aguacate","og_description":"Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.","og_url":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/","og_site_name":"Laylita.com \u2013 Recetas de Cocina","article_publisher":"https:\/\/www.facebook.com\/LaylitaCom","article_author":"https:\/\/www.facebook.com\/LaylitaCom","article_published_time":"2014-03-29T14:46:14+00:00","article_modified_time":"2020-01-16T21:14:19+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","type":"image\/jpeg"}],"author":"Layla Pujol","twitter_card":"summary_large_image","twitter_creator":"@laylita","twitter_site":"@LaylaPujol","twitter_misc":{"Escrito por":"Layla Pujol","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#article","isPartOf":{"@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/"},"author":{"name":"Layla Pujol","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/person\/bb152c0e2cdff3c7b7ab8d516cd8f161"},"headline":"Sanduchitos de hornado de chancho con aguacate","datePublished":"2014-03-29T14:46:14+00:00","dateModified":"2020-01-16T21:14:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/"},"wordCount":388,"commentCount":2,"publisher":{"@id":"https:\/\/www.laylita.com\/recetas\/#organization"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","articleSection":["Bocaditos y snacks","Carne","Cerdo, chancho o puerco","Ecuador","Entradas y Aperitivos","F\u00e1ciles","Latino\/Hispano","Norteamerica","Para ni\u00f1os","Recetas con aguacate o palta","Recetas con sobras y restos de comida","Sanduches","Sudamerica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/","url":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/","name":"Sanduchitos de hornado de chancho o pernil de cerdo con aguacate","isPartOf":{"@id":"https:\/\/www.laylita.com\/recetas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#primaryimage"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","datePublished":"2014-03-29T14:46:14+00:00","dateModified":"2020-01-16T21:14:19+00:00","description":"Sanduchitos de hornado de chancho o pernil de cerdo preparados con aguacate, cebollas encurtidas, y aji criollo o salsa picante de cilantro.","breadcrumb":{"@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#primaryimage","url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","contentUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","width":800,"height":533,"caption":"Sanduchitos de hornado de chancho con aguacate"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laylita.com\/recetas\/sanduchitos-de-hornado-de-chancho-con-aguacate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.laylita.com\/recetas\/"},{"@type":"ListItem","position":2,"name":"Todas las recetas","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/"},{"@type":"ListItem","position":3,"name":"Por plato","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/plato\/"},{"@type":"ListItem","position":4,"name":"Bocaditos y snacks","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/plato\/bocaditos\/"},{"@type":"ListItem","position":5,"name":"Sanduchitos de hornado de chancho con aguacate"}]},{"@type":"WebSite","@id":"https:\/\/www.laylita.com\/recetas\/#website","url":"https:\/\/www.laylita.com\/recetas\/","name":"Laylita.com \u2013 Recetas de Cocina","description":"Encuentra recetas deliciosas y f\u00e1ciles de cocina casera ecuatoriana, latina, e internacional en espa\u00f1ol - con videos y fotos paso a paso.","publisher":{"@id":"https:\/\/www.laylita.com\/recetas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laylita.com\/recetas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laylita.com\/recetas\/#organization","name":"Laylita.com","url":"https:\/\/www.laylita.com\/recetas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/logo\/image\/","url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/04\/Laylita.com-logo.jpg","contentUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/04\/Laylita.com-logo.jpg","width":559,"height":558,"caption":"Laylita.com"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LaylitaCom","https:\/\/x.com\/LaylaPujol","https:\/\/instagram.com\/laylapujol\/","https:\/\/www.pinterest.com\/laylapujol\/","https:\/\/www.youtube.com\/channel\/UCvNX-qrEsv2vNNzG2KXSRag"]},{"@type":"Person","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/person\/bb152c0e2cdff3c7b7ab8d516cd8f161","name":"Layla Pujol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","caption":"Layla Pujol"},"description":"Mi nombre es Layla Pujol, tambi\u00e9n conocida como Laylita, y soy ecuatoriana, aunque actualmente vivo en Europa. Muchas de mis recetas son inspiradas por la comida ecuatoriana, por la cocina americana-mexicana de mi mam\u00e1, quien creci\u00f3 en Nuevo M\u00e9xico, y tambi\u00e9n por la cocina de mi abuelita en Texas.","sameAs":["https:\/\/www.laylita.com\/recetas\/quien-es-laylita\/","https:\/\/www.facebook.com\/LaylitaCom","https:\/\/x.com\/laylita"],"url":"https:\/\/www.laylita.com\/recetas\/author\/laylita\/"}]}},"featured_image_src":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","featured_image_src_square":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","author_info":{"display_name":"Layla Pujol","author_link":"https:\/\/www.laylita.com\/recetas\/author\/laylita\/"},"jetpack_featured_media_url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduchitos-de-hornado-de-chancho-con-aguacate.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgQGB-141","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2319,"url":"https:\/\/www.laylita.com\/recetas\/sanduche-de-chancho\/","url_meta":{"origin":4093,"position":0},"title":"S\u00e1nduche de chancho","author":"Layla Pujol","date":"noviembre 11, 2012","format":false,"excerpt":"El s\u00e1nduche de chancho o de hornado es un s\u00e1nduche t\u00edpico que lleva hornado de chancho o cerdo, cebollas curtidas, rodajas de tomate, aguacate y condimentos al gusto.","rel":"","context":"En \u00abBocaditos y snacks\u00bb","block_context":{"text":"Bocaditos y snacks","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/plato\/bocaditos\/"},"img":{"alt_text":"Sanduche de cerdo","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduche-de-chancho.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduche-de-chancho.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Sanduche-de-chancho.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":188,"url":"https:\/\/www.laylita.com\/recetas\/pernil-lojano\/","url_meta":{"origin":4093,"position":1},"title":"Lomo de Chancho (al estilo del Pernil Lojano)","author":"Layla Pujol","date":"marzo 18, 2008","format":false,"excerpt":"El pernil de chancho se prepara sazonando la carne con un adobo de naranja agria, cebolla, ajo, achiote, clavo de olor, canela, comino y panela, luego se hornea a fuego lento por varias horas.","rel":"","context":"En \u00abCarne\u00bb","block_context":{"text":"Carne","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/carne\/"},"img":{"alt_text":"Un lomo de cerdo asado cortado en rodajas finas en una tabla de picar","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2025\/11\/Lomo-de-chancho-asado-al-estilo-del-pernil-lojano.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2025\/11\/Lomo-de-chancho-asado-al-estilo-del-pernil-lojano.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2025\/11\/Lomo-de-chancho-asado-al-estilo-del-pernil-lojano.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2025\/11\/Lomo-de-chancho-asado-al-estilo-del-pernil-lojano.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2025\/11\/Lomo-de-chancho-asado-al-estilo-del-pernil-lojano.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":142,"url":"https:\/\/www.laylita.com\/recetas\/hornado-de-chancho\/","url_meta":{"origin":4093,"position":2},"title":"Hornado de chancho","author":"Layla Pujol","date":"marzo 5, 2008","format":false,"excerpt":"Receta para hornado de chancho al estilo ecuatoriano, preparado con una pierna de chancho marinada con ali\u00f1o de ajo y comino, ba\u00f1ada con cerveza o chicha, y horneado durante varias horas.","rel":"","context":"En \u00abAndes\u00bb","block_context":{"text":"Andes","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/region-geografica\/sudamerica\/andes\/"},"img":{"alt_text":"Hornado de pierna de chancho al estilo ecuatoriano","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2008\/03\/Hornado-de-pierna-de-chancho-al-estilo-ecuatoriano.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2008\/03\/Hornado-de-pierna-de-chancho-al-estilo-ecuatoriano.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2008\/03\/Hornado-de-pierna-de-chancho-al-estilo-ecuatoriano.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2008\/03\/Hornado-de-pierna-de-chancho-al-estilo-ecuatoriano.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2274,"url":"https:\/\/www.laylita.com\/recetas\/agrio-ecuatoriano\/","url_meta":{"origin":4093,"position":3},"title":"Agrio ecuatoriano","author":"Layla Pujol","date":"noviembre 8, 2012","format":false,"excerpt":"El agrio es una salsa para acompa\u00f1ar a los platos t\u00edpicos de carne de chancho o cerdo, en especial para el hornado.","rel":"","context":"En \u00abAderezos\u00bb","block_context":{"text":"Aderezos","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/por-tipo\/aderezos\/"},"img":{"alt_text":"Un envase de vidrio lleno de la salsa de agrio ecuatoriano","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/11\/Receta-del-agrio-ecuatoriano.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/11\/Receta-del-agrio-ecuatoriano.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/11\/Receta-del-agrio-ecuatoriano.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/11\/Receta-del-agrio-ecuatoriano.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/11\/Receta-del-agrio-ecuatoriano.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3902,"url":"https:\/\/www.laylita.com\/recetas\/lomo-saltado-de-cerdo\/","url_meta":{"origin":4093,"position":4},"title":"Lomo saltado de cerdo","author":"Layla Pujol","date":"enero 24, 2014","format":false,"excerpt":"Receta para lomo saltado de cerdo preparado con lomo de cerdo o chancho, oregano, aj\u00ed o chile en polvo, ajo, cebolla, pimientos, aj\u00edes, tomates, comino, vinagre, salsa de soya, cilantro y cebollita verde. Se sirve con papitas fritas y arroz.","rel":"","context":"En \u00abCarne\u00bb","block_context":{"text":"Carne","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/carne\/"},"img":{"alt_text":"Lomo de cerdo saltado","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Lomo-de-cerdo-saltado.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Lomo-de-cerdo-saltado.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Lomo-de-cerdo-saltado.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Lomo-de-cerdo-saltado.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2287,"url":"https:\/\/www.laylita.com\/recetas\/chancho-o-cerdo-hornado-receta-facil\/","url_meta":{"origin":4093,"position":5},"title":"Chancho o cerdo hornado &#8211; receta f\u00e1cil","author":"Layla Pujol","date":"noviembre 9, 2012","format":false,"excerpt":"El hornado de chancho o cerdo es un plato tradicional Ecuatoriano de chancho asado al horno en un adobo de cerveza o chicha, ajo, comino, y achiote.","rel":"","context":"En \u00abA\u00f1o Nuevo\u00bb","block_context":{"text":"A\u00f1o Nuevo","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ocasiones-y-eventos\/ano-nuevo\/"},"img":{"alt_text":"Hornado ecuatoriano","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Hornado-ecuatoriano-o-cerdo-asado.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/4093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/comments?post=4093"}],"version-history":[{"count":13,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/4093\/revisions"}],"predecessor-version":[{"id":10007,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/4093\/revisions\/10007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/media\/4100"}],"wp:attachment":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/media?parent=4093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/categories?post=4093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/tags?post=4093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}