{"id":2804,"date":"2013-02-14T07:24:30","date_gmt":"2013-02-14T15:24:30","guid":{"rendered":"https:\/\/www.laylita.com\/recetas\/?p=2804"},"modified":"2020-02-27T20:56:49","modified_gmt":"2020-02-28T01:56:49","slug":"coctel-de-granada","status":"publish","type":"post","link":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/","title":{"rendered":"C\u00f3ctel de granada"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este espumoso c\u00f3ctel de granada se prepara con champ\u00e1n o champa\u00f1a y helado o sorbete de granada con tequila.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" data-attachment-id=\"5933\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/coctel-espumante-de-granada\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-title=\"Coctel espumante de granada\" data-image-description=\"&lt;p&gt;Coctel espumante de granada&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada.jpg\" alt=\"Coctel espumante de granada\" class=\"wp-image-5933\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada-640x426.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada-600x400.jpg 600w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumante-de-granada-180x120.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><a title=\"Sparkling pomegranate cocktail\" href=\"https:\/\/www.laylita.com\/recipes\/2013\/02\/14\/sparkling-pomegranate-cocktail\/\" target=\"_blank\" rel=\"noopener noreferrer\">English version<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estaba pensando cual ser\u00eda el mejor nombre para esta bebida, se me ocurri\u00f3 llamarla margarita granizada de granada o mimosa de granada con tequila \u2013 en realidad podr\u00eda decirse que este c\u00f3ctel es el resultado de la uni\u00f3n de ambos. A la final el nombre no importa, resulto ser un refrescante c\u00f3ctel que quedo delicioso y espumoso. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las granadas son perfectas para preparar postres y c\u00f3cteles, pero tambi\u00e9n se las puede usar en platos salados, desde ensaladas hasta platos de carnes. Muchos de estos platillos requieren jugo de granada, es un arduo trabajo convertir la fruta en jugo. Por suerte, muchos supermercados venden jugo de granada que se puede usar para estas recetas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-attachment-id=\"5929\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/coctel-espumoso-de-granada\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-granada.jpg\" data-orig-size=\"683,1024\" data-comments-opened=\"1\" data-image-title=\"Coctel espumoso de granada\" data-image-description=\"&lt;p&gt;Coctel espumoso de granada&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-granada-683x1024.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-granada.jpg\" alt=\"Coctel espumoso de granada\" class=\"wp-image-5929\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-granada.jpg 683w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-granada-427x640.jpg 427w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<br>Prepare un helado tipo sorbete de granada con tequila como base de este c\u00f3ctel, tambi\u00e9n se lo puede preparar como granizado en el caso de no tener una heladera el\u00e9ctrica o m\u00e1quina para preparar helados. Tanto el sorbete como el granizado por si solos pueden servirse como postre, claro que postre solo para adultos si se le pone tequila. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jugo de granada es bastante dulce sin tener que ponerle az\u00facar, pero como se lo va a mezclar con el champan, se le puede poner un poco de az\u00facar o en este caso use un poco de sirope de az\u00facar o jarabe de goma, se lo puede comprar o preparar en casa. El jarabe de goma ayuda a incorporar mejor el dulce al helado o sorbete y tambi\u00e9n ayuda a que la textura del helado no quede granosa. Usted puede ajustar la cantidad de dulce de acuerdo a su gusto.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" data-attachment-id=\"5932\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/coctel-de-champan-y-granada\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" data-orig-size=\"800,534\" data-comments-opened=\"1\" data-image-title=\"Coctel de champan y granada\" data-image-description=\"&lt;p&gt;Coctel de champan y granada para el Dia de San Valentin&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" alt=\"Coctel de champan y granada\" class=\"wp-image-5932\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-768x513.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-600x400.jpg 600w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-180x120.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En cuanto al tequila, usted le puede poner solo un poco para darle un ligero sabor de tequila o le puede poner lo suficiente para que quede bien fuerte. El tequila, aunque sea solo un poco, tambi\u00e9n ayuda a que el sorbete mantenga mantener una textura suave. Claro, con demasiado tequila, no se congelara completamente. Para convertir el helado en c\u00f3ctel, solo se pone una bolita de helado en una copa y se vierte el champan sobre el helado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puede usar cualquier tipo de vino espumoso para esta bebida, ya sea champan, cava, prosecco, etc. Si tiene granadas frescas, puede usar los arilos \u2013 as\u00ed se llaman las semillas de la granada \u2013 para decorar el coctel, le dan un brillo a esta bebida. El sorbete se puede preparar de antemano, hasta varios d\u00edas antes, y asi solo es cuesti\u00f3n de armar el c\u00f3ctel a la hora de servirlo.<\/p>\n\n\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-10394\" class=\"wprm-recipe-container\" data-recipe-id=\"10394\" data-servings=\"10\"><div class=\"wprm-recipe wprm-recipe-template-cutout-v2\"><div class=\"wprm-recipe-image wprm-block-image-rounded\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 10px;border-style: solid;border-color: #ffffff;border-radius: 30px;\" width=\"200\" height=\"134\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" class=\"attachment-200x200 size-200x200\" alt=\"Coctel de champan y granada\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-768x513.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-600x400.jpg 600w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada-180x120.jpg 180w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" data-attachment-id=\"5932\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/coctel-de-champan-y-granada\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" data-orig-size=\"800,534\" data-comments-opened=\"1\" data-image-title=\"Coctel de champan y granada\" data-image-description=\"&lt;p&gt;Coctel de champan y granada para el Dia de San Valentin&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" \/><\/div>\n<div class=\"wprm-recipe-template-cutout-v2-container\">\n\t<div class=\"wprm-recipe-template-cutout-v2-header\">\n\t\t<h2 class=\"wprm-recipe-name wprm-block-text-bold\">C\u00f3ctel de granada<\/h2>\n\t\t<div class=\"wprm-spacer\" style=\"height: 5px;\"><\/div>\n\t\t<div class=\"wprm-recipe-summary wprm-block-text-normal\">C\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.<\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<style>#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-full svg * { fill: #f8e71c; }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-33 svg * { fill: url(#wprm-recipe-user-rating-0-33); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-50 svg * { fill: url(#wprm-recipe-user-rating-0-50); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-66 svg * { fill: url(#wprm-recipe-user-rating-0-66); }linearGradient#wprm-recipe-user-rating-0-33 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-50 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-66 stop { stop-color: #f8e71c; }<\/style><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"0\" height=\"0\" style=\"display:block;width:0px;height:0px\"><defs><linearGradient id=\"wprm-recipe-user-rating-0-33\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-50\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-66\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><\/svg><div id=\"wprm-recipe-user-rating-0\" class=\"wprm-recipe-rating wprm-recipe-rating-recipe-10394 wprm-user-rating wprm-recipe-rating-separate wprm-user-rating-not-voted wprm-user-rating-allowed\" data-recipe=\"10394\" data-average=\"4.89\" data-count=\"35\" data-total=\"171\" data-user=\"0\" data-decimals=\"2\"data-modal-uid=\"user-rating\"><span class=\"wprm-rating-star wprm-rating-star-1 wprm-rating-star-full\" data-rating=\"1\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 1 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-2 wprm-rating-star-full\" data-rating=\"2\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 2 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-3 wprm-rating-star-full\" data-rating=\"3\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 3 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-4 wprm-rating-star-full\" data-rating=\"4\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 4 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-5 wprm-rating-star-full\" data-rating=\"5\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 5 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><div class=\"wprm-recipe-rating-details wprm-block-text-normal\"><span class=\"wprm-recipe-rating-average\">4.89<\/span> de <span class=\"wprm-recipe-rating-count\">35<\/span> votos<\/div><\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<a href=\"https:\/\/www.laylita.com\/recetas\/wprm_print\/coctel-de-granada\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal wprm-recipe-print-inline-button wprm-recipe-link-inline-button wprm-color-accent\" data-recipe-id=\"10394\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Imprimir<\/a>\n\t\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.laylita.com%2Frecetas%2Fcoctel-de-granada%2F&amp;media=https%3A%2F%2Fwww.laylita.com%2Frecetas%2Fwp-content%2Fuploads%2FCoctel-de-champan-y-granada.jpg&amp;description=C%C3%B3ctel+de+granada+preparado+con+sorbete+o+granizado+de+granada+con+tequila+y+champan+o+vino+espumoso.&amp;is_video=false\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"10394\" data-url=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/\" data-media=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" data-description=\"C\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.\" data-repin=\"\" role=\"button\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal wprm-recipe-pin-inline-button wprm-recipe-link-inline-button wprm-color-accent\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\t<a href=\"#commentform\" class=\"wprm-recipe-jump-to-comments wprm-recipe-link wprm-block-text-normal wprm-recipe-jump-to-comments-inline-button wprm-recipe-link-inline-button wprm-color-accent\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\"><span class=\"wprm-recipe-icon wprm-recipe-jump-to-comments-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 16 16\" xml:space=\"preserve\" width=\"16\" height=\"16\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><polygon data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" points=\" 13,0.5 15.5,3 7.5,11 4,12 5,8.5 \"><\/polygon> <line data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" x1=\"11\" y1=\"2.5\" x2=\"13.5\" y2=\"5\"><\/line> <path fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" d=\"M13.5,9.5v5 c0,0.552-0.448,1-1,1h-11c-0.552,0-1-0.448-1-1v-11c0-0.552,0.448-1,1-1h5\"><\/path> <\/g><\/svg><\/span> Preguntas o comentarios<\/a>\n\t\t<div class=\"wprm-spacer\"><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-tags-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-course-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-course-label\">Plato: <\/span><span class=\"wprm-recipe-course wprm-block-text-normal\">Bebidas, Cocteles<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-cuisine-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-cuisine-label\">Cocina: <\/span><span class=\"wprm-recipe-cuisine wprm-block-text-normal\">Fusi\u00f3n, Internacional, Latina, Mexicana<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-keyword-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-keyword-label\">Palabra clave: <\/span><span class=\"wprm-recipe-keyword wprm-block-text-normal\">Champ\u00e1n, C\u00f3ctel de granada, C\u00f3ctel espumoso, Granada, Tequila<\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-times-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-prep-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-prep-time-label\">Tiempo de preparaci\u00f3n: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">30<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-cook-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-cook-time-label\">Tiempo de cocci\u00f3n: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-cook_time wprm-recipe-cook_time-minutes\">5<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-cook_time-unit wprm-recipe-cook_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-total-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-total-time-label\">Tiempo Total: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-total_time wprm-recipe-total_time-minutes\">35<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-total_time-unit wprm-recipe-total_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-servings-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-servings-label\">Rinde: <\/span><span class=\"wprm-recipe-servings-with-unit\"><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-10394 wprm-recipe-servings-adjustable-tooltip wprm-block-text-normal\" data-recipe=\"10394\" aria-label=\"Adjust recipe servings\">10<\/span> <span class=\"wprm-recipe-servings-unit wprm-recipe-details-unit wprm-block-text-normal\">c\u00f3cteles<\/span><\/span><\/div>\n\t\t\n\t\t\n\t<\/div>\n\t<div id=\"recipe-10394-ingredients\" class=\"wprm-recipe-ingredients-container wprm-recipe-ingredients-no-images wprm-recipe-10394-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"10394\" data-servings=\"10\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredientes<\/h3><div class=\"wprm-recipe-ingredient-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-ingredient-group-name wprm-block-text-bold\">Sirope de az\u00facar o jarabe de goma casero<\/h4><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">taza de az\u00facar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">\u00bd<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">taza de agua<\/span><\/li><\/ul><\/div><div class=\"wprm-recipe-ingredient-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-ingredient-group-name wprm-block-text-bold\">Helado o sorbete de granada con tequila<\/h4><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">3<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">tazas de jugo de granada<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">alrededor de 24 oz fl o 710ml<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">\u00bc<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">a \u00bd taza de jarabe simple<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ajuste de acuerdo a su gusto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">El jugo de 2 limones<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">oz<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">&#8211; 8 oz. de tequila<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">ajuste a su gusto<\/span><\/li><\/ul><\/div><div class=\"wprm-recipe-ingredient-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-ingredient-group-name wprm-block-text-bold\">C\u00f3ctel espumoso de granada<\/h4><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">botella de champa\u00f1a o vino espumoso bien helado<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Arilos de granada fresca para decorar<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\"><span class=\"wprm-recipe-ingredient-name\">Az\u00facar para decorar los bordes de las copas<\/span><\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-10394-instructions\" class=\"wprm-recipe-instructions-container wprm-recipe-10394-instructions-container wprm-block-text-normal\" data-recipe=\"10394\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Preparaci\u00f3n<\/h3><div class=\"wprm-recipe-instruction-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-instruction-group-name wprm-block-text-bold\">Sirope de az\u00facar o jarabe de goma casero<\/h4><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10394-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Para preparar el jarabe casero, combine el agua y el az\u00facar en una olla peque\u00f1a.<\/div><\/li><li id=\"wprm-recipe-10394-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Haga hervir, baje el fuego y revuelva bien hasta que el az\u00facar se disuelva completamente.<\/div><\/li><li id=\"wprm-recipe-10394-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Retirar del fuego y deje enfriar antes de usar.<\/div><\/li><\/ul><\/div><div class=\"wprm-recipe-instruction-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-instruction-group-name wprm-block-text-bold\">Helado o sorbete de granada con tequila<\/h4><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10394-step-1-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Mezcle el jugo de granada, jarabe de goma, jugo de lim\u00f3n y tequila.<\/div><\/li><li id=\"wprm-recipe-10394-step-1-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Vierta la mezcla en heladera el\u00e9ctrica o m\u00e1quina para helados  y prep\u00e1relo de acuerdo a las instrucciones de la heladera.<\/div><\/li><li id=\"wprm-recipe-10394-step-1-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Cuando el sorbete o helado est\u00e9 listo, col\u00f3quelo en un recipiente y gu\u00e1rdelo en el congelador hasta la hora de preparar el coctel.<\/div><\/li><\/ul><\/div><div class=\"wprm-recipe-instruction-group\"><h4 class=\"wprm-recipe-group-name wprm-recipe-instruction-group-name wprm-block-text-bold\">C\u00f3ctel espumoso de granada<\/h4><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-10394-step-2-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Coloque una bola de sorbete o granizado en una copa de champagne o cualquier vaso\/copa. Decore el borde de la copa con az\u00facar si lo desea.<\/div><\/li><li id=\"wprm-recipe-10394-step-2-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Cubra la bola de helado con champan o vino espumoso, vierta el champan en peque\u00f1os incrementos para evitar que se desborde.<\/div><\/li><li id=\"wprm-recipe-10394-step-2-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Adorne con los arilos de granada fresca y sirva inmediatamente.<\/div><\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-video\"><\/div>\n\t<div id=\"recipe-10394-notes\" class=\"wprm-recipe-notes-container wprm-block-text-normal\"><h3 class=\"wprm-recipe-header wprm-recipe-notes-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Notas<\/h3><div class=\"wprm-recipe-notes\"><span style=\"display: block;\">Para una variaci\u00f3n sin alcohol de esta bebida, prepare el helado sin tequila y use limonada espumosa en lugar del champan.<\/span><\/div><\/div>\n\t\n<\/div><\/div><\/div>\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champagne-y-granada.jpg\" alt=\"Coctel de champa\u00f1a y granada\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"534\" height=\"800\" data-attachment-id=\"2819\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/coctel-de-granada-2\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-granada.jpg\" data-orig-size=\"534,800\" data-comments-opened=\"1\" data-image-title=\"Coctel de granada\" data-image-description=\"&lt;p&gt;Receta para c\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-granada.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-granada.jpg\" alt=\"Receta del coctel de granada\" class=\"wp-image-2819\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-granada.jpg 534w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-granada-427x640.jpg 427w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-tequila-y-granada.jpg\" alt=\"Coctel de tequila y granada\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Fotos paso a paso para preparar el coctel de granada:<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/1-Granadas-frescas.jpg\" alt=\"Granadas frescas\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2-Ingredientes-para-el-coctel-de-granada.jpg\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2-Ingredientes-para-el-coctel-de-granada.jpg\" alt=\"Ingredientes para el coctel de granada\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/3-Mezcla-de-jugo-de-granada-y-tequila-para-el-sorbete.jpg\" alt=\"3- Mezcla de jugo de granada y tequila para el sorbete\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/4-Sorbete-o-helado-de-granada.jpg\" alt=\"Sorbete o helado de granada\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/5-Granizado-o-granita-de-granada.jpg\" alt=\"Granizado o granita de granada\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/6-Coctel-de-sorbete-de-granada.jpg\" alt=\"Coctel de sorbete de granada\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/7-Coctel-de-champan-y-granada.jpg\" alt=\"Coctel de champan y granada\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/8-Margarita-espumosa-de-granada.jpg\" alt=\"Margarita espumosa de granada\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/9-Coctel-espumoso-de-granada.jpg\" alt=\"Coctel espumoso de granada\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/10-Bebida-de-granada-y-champan.jpg\" alt=\"Bebida de granada y champan\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/11-Mimosa-de-granada-y-tequila.jpg\" alt=\"Mimosa de granada y tequila\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-granada-receta.jpg\" alt=\"Coctel de granada receta\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.<\/p>\n","protected":false},"author":19,"featured_media":5932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[458,74,446,455,9,439,452,438],"tags":[],"class_list":["post-2804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ano-nuevo","category-bebidas","category-cocteles-y-tragos","category-dia-de-los-enamorados","category-frutas","category-latinohispano","category-navidad-y-nochebuena","category-para-fiestas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3ctel de granada - Recetas de Laylita<\/title>\n<meta name=\"description\" content=\"Receta para un refrescante c\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3ctel de granada - Recetas de Laylita\" \/>\n<meta property=\"og:description\" content=\"Receta para un refrescante c\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/\" \/>\n<meta property=\"og:site_name\" content=\"Laylita.com \u2013 Recetas de Cocina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LaylitaCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/LaylitaCom\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-14T15:24:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-28T01:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Layla Pujol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@laylita\" \/>\n<meta name=\"twitter:site\" content=\"@LaylaPujol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Layla Pujol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/\"},\"author\":{\"name\":\"Layla Pujol\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/person\\\/bb152c0e2cdff3c7b7ab8d516cd8f161\"},\"headline\":\"C\u00f3ctel de granada\",\"datePublished\":\"2013-02-14T15:24:30+00:00\",\"dateModified\":\"2020-02-28T01:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/\"},\"wordCount\":784,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Coctel-de-champan-y-granada.jpg\",\"articleSection\":[\"A\u00f1o Nuevo\",\"Bebidas\",\"C\u00f3cteles y tragos\",\"D\u00eda de los Enamorados\",\"Frutas\",\"Latino\\\/Hispano\",\"Navidad y Nochebuena\",\"Para fiestas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/\",\"name\":\"C\u00f3ctel de granada - Recetas de Laylita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Coctel-de-champan-y-granada.jpg\",\"datePublished\":\"2013-02-14T15:24:30+00:00\",\"dateModified\":\"2020-02-28T01:56:49+00:00\",\"description\":\"Receta para un refrescante c\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Coctel-de-champan-y-granada.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/Coctel-de-champan-y-granada.jpg\",\"width\":800,\"height\":534,\"caption\":\"Coctel de champan y granada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/coctel-de-granada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todas las recetas\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Por tipo\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/por-tipo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"C\u00f3cteles y tragos\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/por-tipo\\\/cocteles-y-tragos\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"C\u00f3ctel de granada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#website\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\",\"name\":\"Laylita.com \u2013 Recetas de Cocina\",\"description\":\"Encuentra recetas deliciosas y f\u00e1ciles de cocina casera ecuatoriana, latina, e internacional en espa\u00f1ol - con videos y fotos paso a paso.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\",\"name\":\"Laylita.com\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Laylita.com-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Laylita.com-logo.jpg\",\"width\":559,\"height\":558,\"caption\":\"Laylita.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LaylitaCom\",\"https:\\\/\\\/x.com\\\/LaylaPujol\",\"https:\\\/\\\/instagram.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvNX-qrEsv2vNNzG2KXSRag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/person\\\/bb152c0e2cdff3c7b7ab8d516cd8f161\",\"name\":\"Layla Pujol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"caption\":\"Layla Pujol\"},\"description\":\"Mi nombre es Layla Pujol, tambi\u00e9n conocida como Laylita, y soy ecuatoriana, aunque actualmente vivo en Europa. Muchas de mis recetas son inspiradas por la comida ecuatoriana, por la cocina americana-mexicana de mi mam\u00e1, quien creci\u00f3 en Nuevo M\u00e9xico, y tambi\u00e9n por la cocina de mi abuelita en Texas.\",\"sameAs\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/quien-es-laylita\\\/\",\"https:\\\/\\\/www.facebook.com\\\/LaylitaCom\",\"https:\\\/\\\/x.com\\\/laylita\"],\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/author\\\/laylita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3ctel de granada - Recetas de Laylita","description":"Receta para un refrescante c\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3ctel de granada - Recetas de Laylita","og_description":"Receta para un refrescante c\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.","og_url":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/","og_site_name":"Laylita.com \u2013 Recetas de Cocina","article_publisher":"https:\/\/www.facebook.com\/LaylitaCom","article_author":"https:\/\/www.facebook.com\/LaylitaCom","article_published_time":"2013-02-14T15:24:30+00:00","article_modified_time":"2020-02-28T01:56:49+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","type":"image\/jpeg"}],"author":"Layla Pujol","twitter_card":"summary_large_image","twitter_creator":"@laylita","twitter_site":"@LaylaPujol","twitter_misc":{"Escrito por":"Layla Pujol","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#article","isPartOf":{"@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/"},"author":{"name":"Layla Pujol","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/person\/bb152c0e2cdff3c7b7ab8d516cd8f161"},"headline":"C\u00f3ctel de granada","datePublished":"2013-02-14T15:24:30+00:00","dateModified":"2020-02-28T01:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/"},"wordCount":784,"commentCount":1,"publisher":{"@id":"https:\/\/www.laylita.com\/recetas\/#organization"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","articleSection":["A\u00f1o Nuevo","Bebidas","C\u00f3cteles y tragos","D\u00eda de los Enamorados","Frutas","Latino\/Hispano","Navidad y Nochebuena","Para fiestas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/","url":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/","name":"C\u00f3ctel de granada - Recetas de Laylita","isPartOf":{"@id":"https:\/\/www.laylita.com\/recetas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#primaryimage"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","datePublished":"2013-02-14T15:24:30+00:00","dateModified":"2020-02-28T01:56:49+00:00","description":"Receta para un refrescante c\u00f3ctel de granada preparado con sorbete o granizado de granada con tequila y champan o vino espumoso.","breadcrumb":{"@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#primaryimage","url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","contentUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","width":800,"height":534,"caption":"Coctel de champan y granada"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laylita.com\/recetas\/coctel-de-granada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.laylita.com\/recetas\/"},{"@type":"ListItem","position":2,"name":"Todas las recetas","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/"},{"@type":"ListItem","position":3,"name":"Por tipo","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/por-tipo\/"},{"@type":"ListItem","position":4,"name":"C\u00f3cteles y tragos","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/por-tipo\/cocteles-y-tragos\/"},{"@type":"ListItem","position":5,"name":"C\u00f3ctel de granada"}]},{"@type":"WebSite","@id":"https:\/\/www.laylita.com\/recetas\/#website","url":"https:\/\/www.laylita.com\/recetas\/","name":"Laylita.com \u2013 Recetas de Cocina","description":"Encuentra recetas deliciosas y f\u00e1ciles de cocina casera ecuatoriana, latina, e internacional en espa\u00f1ol - con videos y fotos paso a paso.","publisher":{"@id":"https:\/\/www.laylita.com\/recetas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laylita.com\/recetas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laylita.com\/recetas\/#organization","name":"Laylita.com","url":"https:\/\/www.laylita.com\/recetas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/logo\/image\/","url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/04\/Laylita.com-logo.jpg","contentUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/04\/Laylita.com-logo.jpg","width":559,"height":558,"caption":"Laylita.com"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LaylitaCom","https:\/\/x.com\/LaylaPujol","https:\/\/instagram.com\/laylapujol\/","https:\/\/www.pinterest.com\/laylapujol\/","https:\/\/www.youtube.com\/channel\/UCvNX-qrEsv2vNNzG2KXSRag"]},{"@type":"Person","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/person\/bb152c0e2cdff3c7b7ab8d516cd8f161","name":"Layla Pujol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","caption":"Layla Pujol"},"description":"Mi nombre es Layla Pujol, tambi\u00e9n conocida como Laylita, y soy ecuatoriana, aunque actualmente vivo en Europa. Muchas de mis recetas son inspiradas por la comida ecuatoriana, por la cocina americana-mexicana de mi mam\u00e1, quien creci\u00f3 en Nuevo M\u00e9xico, y tambi\u00e9n por la cocina de mi abuelita en Texas.","sameAs":["https:\/\/www.laylita.com\/recetas\/quien-es-laylita\/","https:\/\/www.facebook.com\/LaylitaCom","https:\/\/x.com\/laylita"],"url":"https:\/\/www.laylita.com\/recetas\/author\/laylita\/"}]}},"featured_image_src":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","featured_image_src_square":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","author_info":{"display_name":"Layla Pujol","author_link":"https:\/\/www.laylita.com\/recetas\/author\/laylita\/"},"jetpack_shortlink":"https:\/\/wp.me\/pgQGB-Je","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":2824,"url":"https:\/\/www.laylita.com\/recetas\/granita-o-granizado-de-granada\/","url_meta":{"origin":2804,"position":0},"title":"Granita o granizado de granada {Raspado de granada}","author":"Layla Pujol","date":"febrero 27, 2013","format":false,"excerpt":"Receta f\u00e1cil para preparar granita o granizado de granada casero con jugo de granada, jugo de lim\u00f3n, az\u00facar y tequila.","rel":"","context":"En \u00abBebidas\u00bb","block_context":{"text":"Bebidas","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/plato\/bebidas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Granizados-caseros-de-granada.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Granizados-caseros-de-granada.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Granizados-caseros-de-granada.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":5914,"url":"https:\/\/www.laylita.com\/recetas\/coctel-espumoso-de-naranja-roja-y-campari\/","url_meta":{"origin":2804,"position":1},"title":"Coctel espumoso de naranja roja y Campari","author":"Layla Pujol","date":"enero 29, 2016","format":false,"excerpt":"Un coctel espumoso de naranja roja y Campari, preparando con jugo de naranja roja o sanguina, licor Campari, y champan o vino espumante (cava o prosecco).","rel":"","context":"En \u00abA\u00f1o Nuevo\u00bb","block_context":{"text":"A\u00f1o Nuevo","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ocasiones-y-eventos\/ano-nuevo\/"},"img":{"alt_text":"Coctel espumoso de naranja roja y Campari","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-naranja-roja-y-Campari.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-naranja-roja-y-Campari.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-naranja-roja-y-Campari.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-espumoso-de-naranja-roja-y-Campari.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3592,"url":"https:\/\/www.laylita.com\/recetas\/coctel-de-sandia\/","url_meta":{"origin":2804,"position":2},"title":"C\u00f3ctel de sand\u00eda {Mimosa de sand\u00eda o patilla}","author":"Layla Pujol","date":"agosto 13, 2013","format":false,"excerpt":"Delicioso y refrescante c\u00f3ctel de sand\u00eda preparado con sand\u00eda, jugo de naranja, az\u00facar, champa\u00f1a o vino espumoso, y decorado con menta fresca.","rel":"","context":"En \u00abBebidas\u00bb","block_context":{"text":"Bebidas","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/plato\/bebidas\/"},"img":{"alt_text":"Coctel mimosa de sand\u00eda","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-mimosa-de-sandia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-mimosa-de-sandia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-mimosa-de-sandia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-mimosa-de-sandia.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3089,"url":"https:\/\/www.laylita.com\/recetas\/kir-royal\/","url_meta":{"origin":2804,"position":3},"title":"Kir royal","author":"Layla Pujol","date":"abril 17, 2013","format":false,"excerpt":"El kir royal, tambi\u00e9n conocido como kir royale, es un cl\u00e1sico c\u00f3ctel espumoso franc\u00e9s preparado con champ\u00e1n y licor de grosellas negras","rel":"","context":"En \u00abA\u00f1o Nuevo\u00bb","block_context":{"text":"A\u00f1o Nuevo","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ocasiones-y-eventos\/ano-nuevo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Receta-del-kir-royal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Receta-del-kir-royal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Receta-del-kir-royal.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":4151,"url":"https:\/\/www.laylita.com\/recetas\/margaritas-de-fresa-o-frutilla\/","url_meta":{"origin":2804,"position":4},"title":"Margaritas de fresa o frutilla","author":"Layla Pujol","date":"abril 6, 2014","format":false,"excerpt":"Receta f\u00e1cil para preparar margaritas de fresa o frutilla. Este delicioso coctel se prepara con fresas o frutillas, jugo de lim\u00f3n, az\u00facar o miel, licor de naranja, y tequila. Se puede preparar como coctel liquido o estilo frape o granizado.","rel":"","context":"En \u00abBebidas\u00bb","block_context":{"text":"Bebidas","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/plato\/bebidas\/"},"img":{"alt_text":"Receta para margaritas de fresa o frutilla","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Receta-para-margaritas-de-fresa-o-frutilla.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Receta-para-margaritas-de-fresa-o-frutilla.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Receta-para-margaritas-de-fresa-o-frutilla.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Receta-para-margaritas-de-fresa-o-frutilla.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5900,"url":"https:\/\/www.laylita.com\/recetas\/cubos-congelados-de-fresas-y-champan\/","url_meta":{"origin":2804,"position":5},"title":"Cubos congelados de fresas y champ\u00e1n","author":"Layla Pujol","date":"enero 27, 2016","format":false,"excerpt":"Cubos congelados de fresas y champ\u00e1n, estos cubitos de hielo de frutilla y champagne son perfectos para complementar cocteles espumantes, sangr\u00eda de vino blanco, o simplemente para darle un toque especial a su copa de champ\u00e1n.","rel":"","context":"En \u00abBebidas\u00bb","block_context":{"text":"Bebidas","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/plato\/bebidas\/"},"img":{"alt_text":"Cubos congelados de fresas y champ\u00e1n","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Cubos-congelados-de-fresas-y-champ%C3%A1n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Cubos-congelados-de-fresas-y-champ%C3%A1n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Cubos-congelados-de-fresas-y-champ%C3%A1n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Cubos-congelados-de-fresas-y-champ%C3%A1n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/Coctel-de-champan-y-granada.jpg","_links":{"self":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/2804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/comments?post=2804"}],"version-history":[{"count":9,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/2804\/revisions"}],"predecessor-version":[{"id":10414,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/2804\/revisions\/10414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/media\/5932"}],"wp:attachment":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/media?parent=2804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/categories?post=2804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/tags?post=2804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}