{"id":13666,"date":"2022-01-14T11:13:00","date_gmt":"2022-01-14T16:13:00","guid":{"rendered":"https:\/\/www.laylita.com\/recetas\/?p=13666"},"modified":"2024-09-24T09:28:32","modified_gmt":"2024-09-24T14:28:32","slug":"pollo-agridulce","status":"publish","type":"post","link":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/","title":{"rendered":"Pollo Agridulce Chino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Una receta casera y f\u00e1cil para preparar pollo agridulce al estilo chino. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, huevo, harina, y aceite.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"13671\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/como-hacer-el-pollo-agridulce-en-casa\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Como hacer el pollo agridulce en casa\" data-image-description=\"&lt;p&gt;Receta f\u00e1cil para preparar pollo agridulce casero. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-1024x683.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-1024x683.jpg\" alt=\"Como hacer el pollo agridulce en casa\" class=\"wp-image-13671\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">El pollo agridulce es un infaltable a la hora de comer comida china, todos los que somos fan\u00e1ticos de la amplia gastronom\u00eda asi\u00e1tica conocemos y disfrutamos de este delicioso plato cada vez que visitamos un restaurante de cocina china.<\/p>\n\n\n<a href=\"#wprm-recipe-container-13667\" data-recipe=\"13667\" style=\"color: #333333;\" class=\"wprm-recipe-jump wprm-recipe-link wprm-jump-to-recipe-shortcode wprm-block-text-normal\">Saltar a la receta<\/a>\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1200\" data-attachment-id=\"13685\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/pollo-agridulce-2\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce.jpg\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-title=\"Pollo agridulce chino\" data-image-description=\"&lt;p&gt;Una receta casera y f\u00e1cil para preparar pollo agridulce casero. &lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-683x1024.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce.jpg\" alt=\"Pollo agridulce\" class=\"wp-image-13685\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-427x640.jpg 427w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-683x1024.jpg 683w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-768x1152.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, y muy curiosamente, este plato no se consume en China, la verdad es que la salsa agridulce solo la consigues en platos en base a pescados, pero no para el pollo, cerdo o res.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfD\u00f3nde se origina la receta de pollo agridulce?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta es sencilla, los mismos inmigrantes chinos adaptaron su gastronom\u00eda al paladar occidental. El origen de esta receta est\u00e1 en las comunidades chinas asentadas en los Estados Unidos. Desde all\u00ed se popularizado al resto de los pa\u00edses occidentales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"13689\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/receta-del-pollo-agridulce-chino\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Receta-del-pollo-agridulce-chino.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Receta del pollo agridulce chino\" data-image-description=\"&lt;p&gt;Receta f\u00e1cil para preparar pollo agridulce casero. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Receta-del-pollo-agridulce-chino-1024x683.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Receta-del-pollo-agridulce-chino-1024x683.jpg\" alt=\"Receta del pollo agridulce chino\" class=\"wp-image-13689\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Receta-del-pollo-agridulce-chino-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Receta-del-pollo-agridulce-chino-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Receta-del-pollo-agridulce-chino-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Receta-del-pollo-agridulce-chino.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La gastronom\u00eda china tradicional, contiene sabores y texturas que pueden resultar muy diferentes a lo que nuestro paladar est\u00e1 acostumbrado. Abundan los sabores picantes y arom\u00e1ticos, y en otros casos ingredientes que puedan resultarnos incre\u00edbles.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1200\" data-attachment-id=\"13684\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/pollo-agridulce-chino\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-chino.jpg\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-title=\"Pollo agridulce chino\" data-image-description=\"&lt;p&gt;Una receta casera y f\u00e1cil para preparar pollo agridulce casero. &lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-chino-683x1024.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-chino.jpg\" alt=\"Pollo agridulce chino\" class=\"wp-image-13684\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-chino.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-chino-427x640.jpg 427w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-chino-683x1024.jpg 683w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-chino-768x1152.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, volviendo a este pollo a lo agridulce, definitivamente es un plato creado por chinos, pero no en China. Es tan popular y delicioso que bien vale la pena aprender a hacerlo en casa. Especialmente para esos d\u00edas que nos provoque darnos un gusto sin salir del hogar o sencillamente sorprender a nuestros amigos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1l es el secreto del pollo agridulce chino?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El pollo con salsa agridulce, b\u00e1sicamente tiene dos elementos principales, el pollo y la salsa agridulce. Uno depende completamente del otro para lograr ese sabor tan especial.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"13686\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/pollo-en-salsa-agridulce-al-estilo-chino\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Pollo en salsa agridulce al estilo chino\" data-image-description=\"&lt;p&gt;Receta f\u00e1cil para preparar pollo agridulce casero. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-1024x683.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-1024x683.jpg\" alt=\"Pollo en salsa agridulce al estilo chino\" class=\"wp-image-13686\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al pollo, hay que elegir una buena pechuga (o m\u00e1s de una dependiendo de la cantidad que quieras preparar), y cortarla en tiras o cubos. Cualquiera de las dos formas te dar\u00e1 un buen resultado. Luego hay que colocar esas tiras o cubos en un bol con ajo, jengibre, sal y pimienta. De esta manera la carne del pollo absorber\u00e1 un delicioso y arom\u00e1tico sabor. Mientras m\u00e1s tiempo lo marines m\u00e1s intenso ser\u00e1 el sabor del pollo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1200\" data-attachment-id=\"13683\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/pollo-agridulce-casero\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-casero.jpg\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-title=\"Pollo agridulce casero\" data-image-description=\"&lt;p&gt;Una receta casera y f\u00e1cil para preparar pollo agridulce casero. &lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-casero-683x1024.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-casero.jpg\" alt=\"Pollo agridulce casero\" class=\"wp-image-13683\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-casero.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-casero-427x640.jpg 427w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-casero-683x1024.jpg 683w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-casero-768x1152.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, para la salsa agridulce, debes tener salsa de tomate k\u00e9tchup, vinagre, agua, salsa de soya y az\u00facar. Es tan sencillo como mezclar muy bien todo en un bol y luego llevar al fuego hasta que hierva. Siempre puedes agregar m\u00e1s k\u00e9tchup si deseas un color rojo m\u00e1s intenso. Tambi\u00e9n puedes ajustar la acidez o dulzura a tu gusto.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"13687\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/pollo-en-salsa-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Pollo en salsa agridulce\" data-image-description=\"&lt;p&gt;Receta f\u00e1cil para preparar pollo agridulce casero. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-1024x683.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-1024x683.jpg\" alt=\"Pollo en salsa agridulce\" class=\"wp-image-13687\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acompa\u00f1antes ideales para el pollo en salsa agridulce<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pollo en salsa agridulce adem\u00e1s de ser un plato delicioso, tambi\u00e9n es muy vers\u00e1til. Por lo general se puede acompa\u00f1ar de arroz blanco (receta chino-americana original). Tambi\u00e9n va bien con arroz chino frito o con papas en diferentes formas, hervidas, fritas o en <a href=\"https:\/\/www.laylita.com\/recetas\/pure-de-papas\/\">pur\u00e9<\/a>. Incluso es posible usar otros acompa\u00f1antes, como vegetales o tallarines. Puedes usar tu creatividad y usar la guarnici\u00f3n de tu preferencia.<\/p>\n\n\n<div id=\"recipe\"><\/div><div id=\"wprm-recipe-container-13667\" class=\"wprm-recipe-container\" data-recipe-id=\"13667\" data-servings=\"4\"><div class=\"wprm-recipe wprm-recipe-template-cutout-v2\"><div class=\"wprm-recipe-image wprm-block-image-rounded\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 10px;border-style: solid;border-color: #ffffff;border-radius: 30px;\" width=\"200\" height=\"200\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-360x361.jpg\" class=\"attachment-200x200 size-200x200\" alt=\"Como hacer el pollo agridulce en casa\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-360x361.jpg 360w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-150x150.jpg 150w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-720x722.jpg 720w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-500x500.jpg 500w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-45x45.jpg 45w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" data-attachment-id=\"13671\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/como-hacer-el-pollo-agridulce-en-casa\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Como hacer el pollo agridulce en casa\" data-image-description=\"&lt;p&gt;Receta f\u00e1cil para preparar pollo agridulce casero. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa-1024x683.jpg\" \/><\/div>\n<div class=\"wprm-recipe-template-cutout-v2-container\">\n\t<div class=\"wprm-recipe-template-cutout-v2-header\">\n\t\t<h2 class=\"wprm-recipe-name wprm-block-text-bold\">Pollo Agridulce Chino<\/h2>\n\t\t<div class=\"wprm-spacer\" style=\"height: 5px;\"><\/div>\n\t\t<div class=\"wprm-recipe-summary wprm-block-text-normal\"><span style=\"display: block;\">Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite.<\/span><\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<style>#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-full svg * { fill: #f8e71c; }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-33 svg * { fill: url(#wprm-recipe-user-rating-0-33); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-50 svg * { fill: url(#wprm-recipe-user-rating-0-50); }#wprm-recipe-user-rating-0 .wprm-rating-star.wprm-rating-star-66 svg * { fill: url(#wprm-recipe-user-rating-0-66); }linearGradient#wprm-recipe-user-rating-0-33 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-50 stop { stop-color: #f8e71c; }linearGradient#wprm-recipe-user-rating-0-66 stop { stop-color: #f8e71c; }<\/style><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"0\" height=\"0\" style=\"display:block;width:0px;height:0px\"><defs><linearGradient id=\"wprm-recipe-user-rating-0-33\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"1\" \/><stop offset=\"33%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-50\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"1\" \/><stop offset=\"50%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><defs><linearGradient id=\"wprm-recipe-user-rating-0-66\"><stop offset=\"0%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"1\" \/><stop offset=\"66%\" stop-opacity=\"0\" \/><stop offset=\"100%\" stop-opacity=\"0\" \/><\/linearGradient><\/defs><\/svg><div id=\"wprm-recipe-user-rating-0\" class=\"wprm-recipe-rating wprm-recipe-rating-recipe-13667 wprm-user-rating wprm-recipe-rating-separate wprm-user-rating-not-voted wprm-user-rating-allowed\" data-recipe=\"13667\" data-average=\"4.95\" data-count=\"20\" data-total=\"99\" data-user=\"0\" data-decimals=\"2\"data-modal-uid=\"user-rating\"><span class=\"wprm-rating-star wprm-rating-star-1 wprm-rating-star-full\" data-rating=\"1\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 1 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-2 wprm-rating-star-full\" data-rating=\"2\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 2 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-3 wprm-rating-star-full\" data-rating=\"3\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 3 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-4 wprm-rating-star-full\" data-rating=\"4\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 4 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><span class=\"wprm-rating-star wprm-rating-star-5 wprm-rating-star-full\" data-rating=\"5\" data-color=\"#f8e71c\" role=\"button\" tabindex=\"0\" aria-label=\"Valorar esta receta con 5 de 5 estrellas\" onmouseenter=\"window.WPRecipeMaker.userRating.enter(this)\" onfocus=\"window.WPRecipeMaker.userRating.enter(this)\" onmouseleave=\"window.WPRecipeMaker.userRating.leave(this)\" onblur=\"window.WPRecipeMaker.userRating.leave(this)\" onclick=\"window.WPRecipeMaker.userRating.click(this, event)\" onkeypress=\"window.WPRecipeMaker.userRating.click(this, event)\" style=\"font-size: 1em;\"><svg width=\"16px\" height=\"16px\" version=\"1.1\" viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"none\" stroke=\"#f8e71c\" stroke-width=\"2\" stroke-linejoin=\"round\" d=\"M11.99,1.94c-.35,0-.67.19-.83.51l-2.56,5.2c-.11.24-.34.4-.61.43l-5.75.83c-.35.05-.64.3-.74.64-.11.34,0,.7.22.94l4.16,4.05c.19.19.27.45.22.7l-.98,5.72c-.06.35.1.7.37.9.29.21.66.24.98.08l5.14-2.71h0c.24-.13.51-.13.75,0l5.14,2.71c.32.16.69.13.98-.08.29-.21.43-.56.37-.9l-.98-5.72h0c-.05-.26.05-.53.22-.7l4.16-4.05h0c.26-.24.34-.61.22-.94s-.4-.58-.74-.64l-5.75-.83c-.26-.03-.48-.21-.61-.43l-2.56-5.2c-.16-.32-.48-.53-.83-.51,0,0-.02,0-.02,0Z\"\/><\/svg><\/span><div class=\"wprm-recipe-rating-details wprm-block-text-normal\"><span class=\"wprm-recipe-rating-average\">4.95<\/span> de <span class=\"wprm-recipe-rating-count\">20<\/span> votos<\/div><\/div>\n\t\t<div class=\"wprm-spacer\" style=\"height: 15px;\"><\/div>\n\t\t<a href=\"https:\/\/www.laylita.com\/recetas\/wprm_print\/pollo-agridulce-chino\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-print wprm-recipe-link wprm-print-recipe-shortcode wprm-block-text-normal wprm-recipe-print-inline-button wprm-recipe-link-inline-button wprm-color-accent\" data-recipe-id=\"13667\" data-template=\"\" target=\"_blank\" rel=\"nofollow\"><span class=\"wprm-recipe-icon wprm-recipe-print-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"16px\" height=\"16px\" viewBox=\"0 0 24 24\"><g ><path fill=\"#333333\" d=\"M19,5.09V1c0-0.552-0.448-1-1-1H6C5.448,0,5,0.448,5,1v4.09C2.167,5.569,0,8.033,0,11v7c0,0.552,0.448,1,1,1h4v4c0,0.552,0.448,1,1,1h12c0.552,0,1-0.448,1-1v-4h4c0.552,0,1-0.448,1-1v-7C24,8.033,21.833,5.569,19,5.09z M7,2h10v3H7V2z M17,22H7v-9h10V22z M18,10c-0.552,0-1-0.448-1-1c0-0.552,0.448-1,1-1s1,0.448,1,1C19,9.552,18.552,10,18,10z\"\/><\/g><\/svg><\/span> Imprimir<\/a>\n\t\t<a href=\"https:\/\/www.pinterest.com\/pin\/create\/bookmarklet\/?url=https%3A%2F%2Fwww.laylita.com%2Frecetas%2Fpollo-agridulce%2F&amp;media=https%3A%2F%2Fwww.laylita.com%2Frecetas%2Fwp-content%2Fuploads%2F2022%2F03%2FComo-hacer-el-pollo-agridulce-en-casa.jpg&amp;description=Esta+receta+de+pollo+en+salsa+agridulce+lleva+pechuga+o+contramuslo+de+pollo%2C+ajo%2C+jengibre%2C+pimientos+dulces%2C+cebolla%2C+salsa+de+tomate%2C+vinagre%2C+salsa+de+soya%2C+az%C3%BAcar%2C+huevo%2C+harina%2C+y+aceite.&amp;is_video=false\" target=\"_blank\" rel=\"nofollow noopener\" data-recipe=\"13667\" data-url=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/\" data-media=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Como-hacer-el-pollo-agridulce-en-casa.jpg\" data-description=\"Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite.\" data-repin=\"\" role=\"button\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\" class=\"wprm-recipe-pin wprm-recipe-link wprm-block-text-normal wprm-recipe-pin-inline-button wprm-recipe-link-inline-button wprm-color-accent\"><span class=\"wprm-recipe-icon wprm-recipe-pin-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><path fill=\"#333333\" d=\"M12,0C5.4,0,0,5.4,0,12c0,5.1,3.2,9.4,7.6,11.2c-0.1-0.9-0.2-2.4,0-3.4c0.2-0.9,1.4-6,1.4-6S8.7,13,8.7,12 c0-1.7,1-2.9,2.2-2.9c1,0,1.5,0.8,1.5,1.7c0,1-0.7,2.6-1,4c-0.3,1.2,0.6,2.2,1.8,2.2c2.1,0,3.8-2.2,3.8-5.5c0-2.9-2.1-4.9-5-4.9 c-3.4,0-5.4,2.6-5.4,5.2c0,1,0.4,2.1,0.9,2.7c0.1,0.1,0.1,0.2,0.1,0.3c-0.1,0.4-0.3,1.2-0.3,1.4c-0.1,0.2-0.2,0.3-0.4,0.2 c-1.5-0.7-2.4-2.9-2.4-4.6c0-3.8,2.8-7.3,7.9-7.3c4.2,0,7.4,3,7.4,6.9c0,4.1-2.6,7.5-6.2,7.5c-1.2,0-2.4-0.6-2.8-1.4 c0,0-0.6,2.3-0.7,2.9c-0.3,1-1,2.3-1.5,3.1C9.6,23.8,10.8,24,12,24c6.6,0,12-5.4,12-12C24,5.4,18.6,0,12,0z\"><\/path><\/g><\/svg><\/span> Pin<\/a>\n\t\t<a href=\"#commentform\" class=\"wprm-recipe-jump-to-comments wprm-recipe-link wprm-block-text-normal wprm-recipe-jump-to-comments-inline-button wprm-recipe-link-inline-button wprm-color-accent\" style=\"color: #2c3e50;background-color: #ffffff;border-color: #ffffff;border-radius: 0px;padding: 5px 12px;\"><span class=\"wprm-recipe-icon wprm-recipe-jump-to-comments-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 16 16\" xml:space=\"preserve\" width=\"16\" height=\"16\"><g class=\"nc-icon-wrapper\" fill=\"#333333\"><polygon data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" points=\" 13,0.5 15.5,3 7.5,11 4,12 5,8.5 \"><\/polygon> <line data-color=\"color-2\" fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" x1=\"11\" y1=\"2.5\" x2=\"13.5\" y2=\"5\"><\/line> <path fill=\"none\" stroke=\"#333333\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-miterlimit=\"10\" d=\"M13.5,9.5v5 c0,0.552-0.448,1-1,1h-11c-0.552,0-1-0.448-1-1v-11c0-0.552,0.448-1,1-1h5\"><\/path> <\/g><\/svg><\/span> Preguntas o comentarios<\/a>\n\t\t<div class=\"wprm-spacer\"><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-tags-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-course-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-course-label\">Plato: <\/span><span class=\"wprm-recipe-course wprm-block-text-normal\">Plato principal<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-cuisine-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-cuisine-label\">Cocina: <\/span><span class=\"wprm-recipe-cuisine wprm-block-text-normal\">China, Fusi\u00f3n, Internacional, Norteamericana<\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-tag-container wprm-recipe-keyword-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-tag-label wprm-recipe-keyword-label\">Palabra clave: <\/span><span class=\"wprm-recipe-keyword wprm-block-text-normal\">Comida china, Pollo, Pollo agridulce, Salsa agridulce<\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-meta-container wprm-recipe-times-container wprm-recipe-details-container wprm-recipe-details-container-inline wprm-block-text-normal\"><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-prep-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-prep-time-label\">Tiempo de preparaci\u00f3n: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-prep_time wprm-recipe-prep_time-minutes\">20<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-prep_time-unit wprm-recipe-prep_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-time-container wprm-recipe-cook-time-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-time-label wprm-recipe-cook-time-label\">Tiempo de cocci\u00f3n: <\/span><span class=\"wprm-recipe-time wprm-block-text-normal\"><span class=\"wprm-recipe-details wprm-recipe-details-minutes wprm-recipe-cook_time wprm-recipe-cook_time-minutes\">20<span class=\"sr-only screen-reader-text wprm-screen-reader-text\" data-nosnippet> minutos<\/span><\/span> <span class=\"wprm-recipe-details-unit wprm-recipe-details-minutes wprm-recipe-cook_time-unit wprm-recipe-cook_timeunit-minutes\" aria-hidden=\"true\">minutos<\/span><\/span><\/div><\/div>\n\t\t<div class=\"wprm-recipe-block-container wprm-recipe-block-container-inline wprm-block-text-normal wprm-recipe-servings-container\" style=\"\"><span class=\"wprm-recipe-details-label wprm-block-text-faded wprm-recipe-servings-label\">Rinde: <\/span><span class=\"wprm-recipe-servings-with-unit\"><span class=\"wprm-recipe-servings wprm-recipe-details wprm-recipe-servings-13667 wprm-recipe-servings-adjustable-tooltip wprm-block-text-normal\" data-recipe=\"13667\" aria-label=\"Adjust recipe servings\">4<\/span> <span class=\"wprm-recipe-servings-unit wprm-recipe-details-unit wprm-block-text-normal\">porciones<\/span><\/span><\/div>\n\t\t\n\t\t\n\t<\/div>\n\t<div id=\"recipe-13667-ingredients\" class=\"wprm-recipe-ingredients-container wprm-recipe-ingredients-no-images wprm-recipe-13667-ingredients-container wprm-block-text-normal wprm-ingredient-style-regular wprm-recipe-images-before\" data-recipe=\"13667\" data-servings=\"4\"><h3 class=\"wprm-recipe-header wprm-recipe-ingredients-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Ingredientes<\/h3><div class=\"wprm-recipe-ingredient-group\"><ul class=\"wprm-recipe-ingredients\"><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"0\"><span class=\"wprm-recipe-ingredient-amount\">800<\/span>&#32;<span class=\"wprm-recipe-ingredient-unit\">g.<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de carne de pollo sin hueso y sin piel<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">puede usar pechugas o contramuslos<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"1\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">dientes de ajo<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"2\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">ra\u00edz de jengibre<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">20 g.<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"3\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">huevo batido<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"4\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">pimiento dulce verde o piment\u00f3n morr\u00f3n verde<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">150 g.<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"5\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">pimiento dulce rojo o piment\u00f3n morr\u00f3n rojo<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">150 g.<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"6\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">cebolla blanca<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">100 g.<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"7\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">tazas de harina de trigo<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">todo uso, 220 g.<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"8\"><span class=\"wprm-recipe-ingredient-amount\">1<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">taza de salsa de tomate<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">tipo k\u00e9tchup, 200 g<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"9\"><span class=\"wprm-recipe-ingredient-amount\">2\/3<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">de taza de vinagre de vino<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"10\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">cucharadas de salsa de soya<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"11\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">cucharadas de az\u00facar<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">agregue mas o menos a su gusto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"12\"><span class=\"wprm-recipe-ingredient-amount\">2<\/span>&#32;<span class=\"wprm-recipe-ingredient-name\">tazas de aceite vegetal<\/span>&#32;<span class=\"wprm-recipe-ingredient-notes wprm-recipe-ingredient-notes-faded\">480 ml (para fre\u00edr)<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"13\"><span class=\"wprm-recipe-ingredient-name\">Sal y pimienta al gusto<\/span><\/li><li class=\"wprm-recipe-ingredient\" style=\"list-style-type: disc;\" data-uid=\"14\"><span class=\"wprm-recipe-ingredient-name\">Semillas de s\u00e9samo o ajonjol\u00ed tostado para decorar<\/span><\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-13667-instructions\" class=\"wprm-recipe-instructions-container wprm-recipe-13667-instructions-container wprm-block-text-normal\" data-recipe=\"13667\"><h3 class=\"wprm-recipe-header wprm-recipe-instructions-header wprm-block-text-bold wprm-align-left wprm-header-decoration-none\" style=\"\">Preparaci\u00f3n<\/h3><div class=\"wprm-recipe-media-toggle-container wprm-toggle-container wprm-toggle-buttons-container wprm-block-text-normal\" style=\"background-color: #ffffff;border-color: #333333;color: #333333;border-radius: 3px;\"><button class=\"wprm-recipe-media-toggle wprm-toggle wprm-toggle-active\" data-state=\"on\" data-recipe=\"13667\" style=\"background-color: #333333;color: #ffffff;\" aria-label=\"Mostrar las instrucciones multimedia\"><span class=\"wprm-recipe-icon wprm-toggle-icon wprm-toggle-icon-active\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" stroke-linecap=\"square\" stroke-linejoin=\"miter\" stroke-width=\"1\" transform=\"translate(0.5 0.5)\" fill=\"#ffffff\" stroke=\"#ffffff\"><circle data-color=\"color-2\" cx=\"12\" cy=\"13\" r=\"5\" fill=\"none\" stroke-miterlimit=\"10\"\/><path d=\"M21,22H3a2,2,0,0,1-2-2V7A2,2,0,0,1,3,5H7L9,2h6l2,3h4a2,2,0,0,1,2,2V20A2,2,0,0,1,21,22Z\" fill=\"none\" stroke=\"#ffffff\" stroke-miterlimit=\"10\"\/><circle data-color=\"color-2\" data-stroke=\"none\" cx=\"4\" cy=\"8\" r=\"1\" stroke=\"none\"\/><\/g><\/svg><\/span><span class=\"wprm-recipe-icon wprm-toggle-icon wprm-toggle-icon-inactive\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" stroke-linecap=\"square\" stroke-linejoin=\"miter\" stroke-width=\"1\" transform=\"translate(0.5 0.5)\" fill=\"#333333\" stroke=\"#333333\"><circle data-color=\"color-2\" cx=\"12\" cy=\"13\" r=\"5\" fill=\"none\" stroke-miterlimit=\"10\"\/><path d=\"M21,22H3a2,2,0,0,1-2-2V7A2,2,0,0,1,3,5H7L9,2h6l2,3h4a2,2,0,0,1,2,2V20A2,2,0,0,1,21,22Z\" fill=\"none\" stroke=\"#333333\" stroke-miterlimit=\"10\"\/><circle data-color=\"color-2\" data-stroke=\"none\" cx=\"4\" cy=\"8\" r=\"1\" stroke=\"none\"\/><\/g><\/svg><\/span><\/button><button class=\"wprm-recipe-media-toggle wprm-toggle\" data-state=\"off\" data-recipe=\"13667\" style=\"background-color: #333333;color: #ffffff;border-left: 1px solid #333333;\" aria-label=\"Ocultar las instrucciones multimedia\"><span class=\"wprm-recipe-icon wprm-toggle-icon wprm-toggle-icon-active\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" stroke-linecap=\"square\" stroke-linejoin=\"miter\" stroke-width=\"1\" transform=\"translate(0.5 0.5)\" fill=\"#ffffff\" stroke=\"#ffffff\"><circle data-color=\"color-2\" cx=\"12\" cy=\"12\" r=\"4\" fill=\"none\" stroke-miterlimit=\"10\"\/><path d=\"M22,8v9a2,2,0,0,1-2,2H10\" fill=\"none\" stroke=\"#ffffff\" stroke-miterlimit=\"10\"\/><path data-cap=\"butt\" d=\"M2,17V8A2,2,0,0,1,4,6H7L9,3h6l2.4,3.6\" fill=\"none\" stroke=\"#ffffff\" stroke-miterlimit=\"10\" stroke-linecap=\"butt\"\/><line data-cap=\"butt\" data-color=\"color-2\" x1=\"23\" y1=\"1\" x2=\"1\" y2=\"23\" fill=\"none\" stroke-miterlimit=\"10\" stroke-linecap=\"butt\"\/><\/g><\/svg><\/span><span class=\"wprm-recipe-icon wprm-toggle-icon wprm-toggle-icon-inactive\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" viewBox=\"0 0 24 24\"><g class=\"nc-icon-wrapper\" stroke-linecap=\"square\" stroke-linejoin=\"miter\" stroke-width=\"1\" transform=\"translate(0.5 0.5)\" fill=\"#333333\" stroke=\"#333333\"><circle data-color=\"color-2\" cx=\"12\" cy=\"12\" r=\"4\" fill=\"none\" stroke-miterlimit=\"10\"\/><path d=\"M22,8v9a2,2,0,0,1-2,2H10\" fill=\"none\" stroke=\"#333333\" stroke-miterlimit=\"10\"\/><path data-cap=\"butt\" d=\"M2,17V8A2,2,0,0,1,4,6H7L9,3h6l2.4,3.6\" fill=\"none\" stroke=\"#333333\" stroke-miterlimit=\"10\" stroke-linecap=\"butt\"\/><line data-cap=\"butt\" data-color=\"color-2\" x1=\"23\" y1=\"1\" x2=\"1\" y2=\"23\" fill=\"none\" stroke-miterlimit=\"10\" stroke-linecap=\"butt\"\/><\/g><\/svg><\/span><\/button><\/div><div class=\"wprm-recipe-instruction-group\"><ul class=\"wprm-recipe-instructions\"><li id=\"wprm-recipe-13667-step-0-0\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Corte la carne de pollo en cubos de m\u00e1ximo tres cent\u00edmetros de lado.<\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-01-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-01-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-01-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-01-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-01-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13673\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-01-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-01-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-01 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-01-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-1\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Pele los ajos y mach\u00e1quelos, pele el jengibre y r\u00e1llelo por la parte m\u00e1s fina del rallador. Luego, sazone los cubos o trozos de pollo con ajo, jengibre, sal y pimienta. Frotar bien de modo que todos los cubos de pechuga queden impregnados de la marinada. Tape el bol y gu\u00e1rdelo en la nevera marinando por al menos una hora.<\/div><\/li><li id=\"wprm-recipe-13667-step-0-2\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Mientras se marina el pollo, lave muy bien los pimientos. C\u00f3rteles el tallo, extraiga las venas y las semillas. Luego c\u00f3rtelas en cuadros de unos tres cent\u00edmetros de lado. Repita este procedimiento con la cebolla.<\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-03-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-03-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-03-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-03-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-03-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13675\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-03-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-03-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-03 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-03-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-3\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\"><span style=\"display: block;\">Retire el bol con el pollo marinado de la refrigeradora y agregue el huevo, lo puede batir de antemano o mezclar directo con el pollo.  <\/span><\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-02-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-02-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-02-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-02-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-02-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13674\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-02-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-02-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-02 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-02-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-4\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\"><span style=\"display: block;\">La t\u00e9cnica m\u00e1s sencilla, r\u00e1pida y eficiente que he encontrado para rebozar es agregar la harina con la carne a rebozar dentro de un envase pl\u00e1stico con tapa. Luego, colocar la tapa, y revolver hacia los lados por un par de minutos y listo. Todas las piezas quedan perfectamente cubiertas de harina. En este caso, aplicaremos esta t\u00e9cnica. Luego agregue la harina de trigo.<\/span><\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-04-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-04-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-04-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-04-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-04-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13676\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-04-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-04-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-04 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-04-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-5\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Coloque la tapa al bol y b\u00e1talo vigorosamente hacia los lados hasta que todas las piezas queden perfectamente rebozadas. D\u00e9jelas reposando unos minutos para que la harina se humedezca correctamente.<\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-05-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-05-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-05-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-05-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-05-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13677\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-05-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-05-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-05 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-05-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-6\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">En una olla peque\u00f1a coloque la salsa de tomate, el vinagre, la salsa de soya y el az\u00facar. Revu\u00e9lvalo. Luego coc\u00ednelo por unos cinco minutos y listo.  Pruebe y seg\u00fan su gusto puede agregar m\u00e1s de alg\u00fan ingrediente si lo desea. Si est\u00e1 muy agria puede agregar un poco de az\u00facar para darle un poco de balance. Tambi\u00e9n puede a\u00f1adir un poco de pimienta, o salsa picante a esta mezcla. Ap\u00e1guela y d\u00e9jela reposar.<\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-06-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso de la salsa agridulce para pollo\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-06-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-06-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-06-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-06-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13678\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-06-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-06-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-06 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-06-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-7\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">En un sart\u00e9n grande, coloque el aceite y cali\u00e9ntelo a fuego medio alto. Cuando este burbujeando, agregue los cubos de pollo con cuidado. Fr\u00eda cada tanda por unos tres a cinco minutos hasta que est\u00e9n bien doraditos.  Ret\u00edrelos del aceite, y d\u00e9jelos reposando sobre un plato cubierto con papel absorbente.<\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-07-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-07-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-07-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-07-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-07-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13679\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-07-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-07-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-07 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-07-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-8\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\"><span style=\"display: block;\">En una olla grande, agregue los pimentones y las cebollas picados en cubos con una cucharada de aceite y salt\u00e9alos durante unos minutos. <\/span><\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-08-preparacion-del-pollo-agridulce-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-08-preparacion-del-pollo-agridulce-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-08-preparacion-del-pollo-agridulce-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-08-preparacion-del-pollo-agridulce-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-08-preparacion-del-pollo-agridulce.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13680\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-08-preparacion-del-pollo-agridulce\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-08-preparacion-del-pollo-agridulce.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-08 preparacion del pollo agridulce\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-08-preparacion-del-pollo-agridulce-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-9\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\"><span style=\"display: block;\">Luego agrega los trozos de pollo fritos, y la salsa agridulce. Mezcle todo y d\u00e9jelo calentar bien. Si lo considera necesario, incorpore media taza de agua para que la salsa este m\u00e1s fluida. Coc\u00ednelo tapado por unos cinco minutos m\u00e1s o hasta que el pollo este bien cocido y listo.<\/span><\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-09-preparacion-del-pollo-agridulce-chino-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-09-preparacion-del-pollo-agridulce-chino-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-09-preparacion-del-pollo-agridulce-chino-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-09-preparacion-del-pollo-agridulce-chino-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-09-preparacion-del-pollo-agridulce-chino.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13681\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/paso-09-preparacion-del-pollo-agridulce-chino\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-09-preparacion-del-pollo-agridulce-chino.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Paso-09 preparacion del pollo agridulce chino\" data-image-description=\"&lt;p&gt;Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Paso-09-preparacion-del-pollo-agridulce-chino-1024x683.jpg\" \/><\/div> <\/li><li id=\"wprm-recipe-13667-step-0-10\" class=\"wprm-recipe-instruction\" style=\"list-style-type: decimal;\"><div class=\"wprm-recipe-instruction-text\">Sirva acompa\u00f1ado de arroz blanco, y espolvoree por encima con semillas de s\u00e9samo tostadas.  Tambi\u00e9n puede agregarle ceboll\u00edn picado para decorar.<\/div><div class=\"wprm-recipe-instruction-media wprm-recipe-instruction-image\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-640x427.jpg\" class=\"attachment-medium size-medium\" alt=\"Pollo en salsa agridulce al estilo chino\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"13686\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/pollo-en-salsa-agridulce-al-estilo-chino\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Pollo en salsa agridulce al estilo chino\" data-image-description=\"&lt;p&gt;Receta f\u00e1cil para preparar pollo agridulce casero. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino-1024x683.jpg\" \/><\/div> <\/li><\/ul><\/div><\/div>\n\t<div id=\"recipe-video\"><\/div>\n\t\n\t\n<\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Ingredientes y fotos paso a paso de la preparaci\u00f3n del pollo con salsa agridulce:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"13672\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/ingredientes-del-pollo-agridulce-chino\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Ingredientes-del-pollo-agridulce-chino.jpg\" data-orig-size=\"1200,800\" data-comments-opened=\"1\" data-image-title=\"Ingredientes del pollo agridulce chino\" data-image-description=\"&lt;p&gt;Ingredientes del pollo agridulce chino &amp;#8211; Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Ingredientes-del-pollo-agridulce-chino-1024x683.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Ingredientes-del-pollo-agridulce-chino-1024x683.jpg\" alt=\"Ingredientes del pollo agridulce chino\" class=\"wp-image-13672\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Ingredientes-del-pollo-agridulce-chino-1024x683.jpg 1024w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Ingredientes-del-pollo-agridulce-chino-640x427.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Ingredientes-del-pollo-agridulce-chino-768x512.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Ingredientes-del-pollo-agridulce-chino.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ingredientes del pollo agridulce chino<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"2560\" data-attachment-id=\"13688\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/preparacion-paso-a-paso-del-pollo-agridulce-chino\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-scaled.jpg\" data-orig-size=\"640,2560\" data-comments-opened=\"1\" data-image-title=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" data-image-description=\"&lt;p&gt;Preparaci\u00f3n paso a paso del pollo agridulce chino&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-256x1024.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-scaled.jpg\" alt=\"Preparaci\u00f3n paso a paso del pollo agridulce chino\" class=\"wp-image-13688\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-scaled.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-160x640.jpg 160w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-256x1024.jpg 256w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-768x3072.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-384x1536.jpg 384w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Preparacion-paso-a-paso-del-pollo-agridulce-chino-512x2048.jpg 512w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" data-attachment-id=\"13682\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/pollo-agridulce-receta-casera\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-receta-casera.jpg\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-title=\"Pollo agridulce &amp;#8211; receta casera\" data-image-description=\"&lt;p&gt;Una receta casera y f\u00e1cil para preparar pollo agridulce casero. &lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-receta-casera-683x1024.jpg\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-receta-casera-683x1024.jpg\" alt=\"Pollo agridulce - receta casera\" class=\"wp-image-13682\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-receta-casera-683x1024.jpg 683w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-receta-casera-427x640.jpg 427w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-receta-casera-768x1152.jpg 768w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-agridulce-receta-casera.jpg 800w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Otras recetas con pollo que te pueden interesar:<\/h2>\n\n\n<div class=\"wprm-recipe wprm-recipe-roundup-item wprm-recipe-roundup-item-8307 wprm-recipe-template-recetas-roundup-2025\" data-servings=\"12\"><span class=\"wprm-condition wprm-condition-field wprm-condition-field-image\">\n<div class=\"wprm-image-container\">\n  \t<div class=\"wprm-recipe-counter wprm-block-text-bold\">1<\/div>\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;width: 750px;max-width: 100%;height: 500px;object-fit: cover;\" width=\"640\" height=\"427\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/como-hacer-chaulafan.jpg\" class=\"attachment-750x999999 size-750x999999\" alt=\"\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/como-hacer-chaulafan.jpg 640w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/como-hacer-chaulafan-600x400.jpg 600w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/como-hacer-chaulafan-180x120.jpg 180w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" data-attachment-id=\"1249\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/chaulafan-o-arroz-frito-de-pollo\/como-hacer-chaulafan\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/como-hacer-chaulafan.jpg\" data-orig-size=\"640,427\" data-comments-opened=\"1\" data-image-title=\"Chaulafan\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/como-hacer-chaulafan.jpg\" \/><\/div>\n\t\n<\/div>\n<\/span>\n<div class=\"wprm-summary-container\">\n    <div class=\"wprm-recipe-name wprm-block-text-bold\">Chaulafan o arroz frito de pollo<\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <div class=\"wprm-recipe-summary wprm-block-text-normal\">El chaulafan de pollo es la versi\u00f3n ecuatoriana del arroz frito chino preparado con arroz, pollo, tocino, cebolla, ajo, pimientos, arvejas, zanahorias, huevos revueltos, pasas, especias y hierbas.<\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <a href=\"https:\/\/www.laylita.com\/recetas\/chaulafan-o-arroz-frito-de-pollo\/\" style=\"color: #ffffff;background-color: #000000;border-color: #000000;border-radius: 5px;padding: 5px 5px;\" class=\"wprm-recipe-roundup-link wprm-recipe-link wprm-block-text-normal wprm-recipe-roundup-link-inline-button wprm-recipe-link-inline-button wprm-color-accent\" aria-label=\"Chaulafan o arroz frito de pollo\">Ver esta Receta<\/a>\n<\/div><\/div>\n\n<div class=\"wprm-recipe wprm-recipe-roundup-item wprm-recipe-roundup-item-13625 wprm-recipe-template-recetas-roundup-2025\" data-servings=\"4\"><span class=\"wprm-condition wprm-condition-field wprm-condition-field-image\">\n<div class=\"wprm-image-container\">\n  \t<div class=\"wprm-recipe-counter wprm-block-text-bold\">2<\/div>\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;width: 750px;max-width: 100%;height: 500px;object-fit: cover;\" width=\"750\" height=\"1125\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-o-gallina-a-la-Coca-Cola.jpg\" class=\"attachment-750x999999 size-750x999999\" alt=\"Pollo o gallina a la Coca-Cola\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-o-gallina-a-la-Coca-Cola.jpg 800w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-o-gallina-a-la-Coca-Cola-427x640.jpg 427w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-o-gallina-a-la-Coca-Cola-683x1024.jpg 683w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-o-gallina-a-la-Coca-Cola-768x1152.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" data-attachment-id=\"13633\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-a-la-coca-cola\/pollo-o-gallina-a-la-coca-cola\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-o-gallina-a-la-Coca-Cola.jpg\" data-orig-size=\"800,1200\" data-comments-opened=\"1\" data-image-title=\"Pollo o gallina a la Coca-Cola\" data-image-description=\"&lt;p&gt;Receta casera para preparar pollo a la coca cola, esta forma de preparar pollo es f\u00e1cil, r\u00e1pida y deliciosa. Solo lleva presas de pollo, ajo, cebolla, aceite, maicena y coca cola o la gaseosa que tu prefieras.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-o-gallina-a-la-Coca-Cola-683x1024.jpg\" \/><\/div>\n\t\n<\/div>\n<\/span>\n<div class=\"wprm-summary-container\">\n    <div class=\"wprm-recipe-name wprm-block-text-bold\">Pollo a la Coca-Cola<\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <div class=\"wprm-recipe-summary wprm-block-text-normal\"><span style=\"display: block;\">Esta forma de preparar pollo es f\u00e1cil, r\u00e1pida y deliciosa. Solo lleva presas de pollo, ajo, cebolla, aceite, maicena y coca cola o la gaseosa que tu prefieras.<\/span><\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <a href=\"https:\/\/www.laylita.com\/recetas\/pollo-a-la-coca-cola\/\" style=\"color: #ffffff;background-color: #000000;border-color: #000000;border-radius: 5px;padding: 5px 5px;\" class=\"wprm-recipe-roundup-link wprm-recipe-link wprm-block-text-normal wprm-recipe-roundup-link-inline-button wprm-recipe-link-inline-button wprm-color-accent\" aria-label=\"Pollo a la Coca-Cola\">Ver esta Receta<\/a>\n<\/div><\/div>\n\n<div class=\"wprm-recipe wprm-recipe-roundup-item wprm-recipe-roundup-item-9417 wprm-recipe-template-recetas-roundup-2025\" data-servings=\"10\"><span class=\"wprm-condition wprm-condition-field wprm-condition-field-image\">\n<div class=\"wprm-image-container\">\n  \t<div class=\"wprm-recipe-counter wprm-block-text-bold\">3<\/div>\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;width: 750px;max-width: 100%;height: 500px;object-fit: cover;\" width=\"750\" height=\"1124\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/10\/Pollo-o-gallina-cocido-en-chicha.jpg\" class=\"attachment-750x999999 size-750x999999\" alt=\"Pollo o gallina cocido en chicha\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/10\/Pollo-o-gallina-cocido-en-chicha.jpg 801w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/10\/Pollo-o-gallina-cocido-en-chicha-427x640.jpg 427w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/10\/Pollo-o-gallina-cocido-en-chicha-684x1024.jpg 684w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/10\/Pollo-o-gallina-cocido-en-chicha-768x1151.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" data-attachment-id=\"9427\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/fritada-de-gallina-o-pollo\/pollo-o-gallina-cocido-en-chicha\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/10\/Pollo-o-gallina-cocido-en-chicha.jpg\" data-orig-size=\"801,1200\" data-comments-opened=\"1\" data-image-title=\"Pollo o gallina cocido en chicha\" data-image-description=\"&lt;p&gt;La fritada de gallina se prepara cocinando presas de gallina o pollo en un adobo de chicha, ajo, cebolla y comino, se cocina hasta que el liquido se reduzca y el pollo quede dorado.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2012\/10\/Pollo-o-gallina-cocido-en-chicha-684x1024.jpg\" \/><\/div>\n\t\n<\/div>\n<\/span>\n<div class=\"wprm-summary-container\">\n    <div class=\"wprm-recipe-name wprm-block-text-bold\">Fritada de gallina o pollo<\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <div class=\"wprm-recipe-summary wprm-block-text-normal\"><span style=\"display: block;\">La fritada de gallina se prepara cocinando presas de gallina o pollo en un adobo de chicha, ajo, cebolla y comino, se cocina hasta que el liquido se reduzca y el pollo quede dorado. <\/span><\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <a href=\"https:\/\/www.laylita.com\/recetas\/fritada-de-gallina-o-pollo\/\" style=\"color: #ffffff;background-color: #000000;border-color: #000000;border-radius: 5px;padding: 5px 5px;\" class=\"wprm-recipe-roundup-link wprm-recipe-link wprm-block-text-normal wprm-recipe-roundup-link-inline-button wprm-recipe-link-inline-button wprm-color-accent\" aria-label=\"Fritada de gallina o pollo\">Ver esta Receta<\/a>\n<\/div><\/div>\n\n<div class=\"wprm-recipe wprm-recipe-roundup-item wprm-recipe-roundup-item-13225 wprm-recipe-template-recetas-roundup-2025\" data-servings=\"4\"><span class=\"wprm-condition wprm-condition-field wprm-condition-field-image\">\n<div class=\"wprm-image-container\">\n  \t<div class=\"wprm-recipe-counter wprm-block-text-bold\">4<\/div>\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;width: 750px;max-width: 100%;height: 500px;object-fit: cover;\" width=\"750\" height=\"998\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2021\/12\/Como-hacer-pechugas-de-pollo-rellenas.jpg\" class=\"attachment-750x999999 size-750x999999\" alt=\"Como hacer pechugas de pollo rellenas\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2021\/12\/Como-hacer-pechugas-de-pollo-rellenas.jpg 902w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2021\/12\/Como-hacer-pechugas-de-pollo-rellenas-481x640.jpg 481w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2021\/12\/Como-hacer-pechugas-de-pollo-rellenas-770x1024.jpg 770w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2021\/12\/Como-hacer-pechugas-de-pollo-rellenas-768x1022.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" data-attachment-id=\"13231\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pechuga-de-pollo-rellena-de-queso-y-espinaca\/como-hacer-pechugas-de-pollo-rellenas\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2021\/12\/Como-hacer-pechugas-de-pollo-rellenas.jpg\" data-orig-size=\"902,1200\" data-comments-opened=\"1\" data-image-title=\"Como hacer pechugas de pollo rellenas\" data-image-description=\"&lt;p&gt;Receta f\u00e1cil para preparar pechuga de pollo rellena de queso y espinaca. Estas pechugas rellenas son sencillas y deliciosas, perfectas para una cena especial. Tambi\u00e9n se pueden preparar con pavo.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2021\/12\/Como-hacer-pechugas-de-pollo-rellenas-770x1024.jpg\" \/><\/div>\n\t\n<\/div>\n<\/span>\n<div class=\"wprm-summary-container\">\n    <div class=\"wprm-recipe-name wprm-block-text-bold\">Pechuga de pollo rellena de queso y espinaca<\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <div class=\"wprm-recipe-summary wprm-block-text-normal\"><span style=\"display: block;\">Receta de pechuga de pollo rellena de queso y espinaca. Estas pechugas rellenas tambi\u00e9n se pueden preparar con pavo.<\/span><\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <a href=\"https:\/\/www.laylita.com\/recetas\/pechuga-de-pollo-rellena-de-queso-y-espinaca\/\" style=\"color: #ffffff;background-color: #000000;border-color: #000000;border-radius: 5px;padding: 5px 5px;\" class=\"wprm-recipe-roundup-link wprm-recipe-link wprm-block-text-normal wprm-recipe-roundup-link-inline-button wprm-recipe-link-inline-button wprm-color-accent\" aria-label=\"Pechuga de pollo rellena de queso y espinaca\">Ver esta Receta<\/a>\n<\/div><\/div>\n\n<div class=\"wprm-recipe wprm-recipe-roundup-item wprm-recipe-roundup-item-8646 wprm-recipe-template-recetas-roundup-2025\" data-servings=\"4\"><span class=\"wprm-condition wprm-condition-field wprm-condition-field-image\">\n<div class=\"wprm-image-container\">\n  \t<div class=\"wprm-recipe-counter wprm-block-text-bold\">5<\/div>\n\t<div class=\"wprm-recipe-image wprm-block-image-normal\"><img loading=\"lazy\" decoding=\"async\" style=\"border-width: 0px;border-style: solid;border-color: #666666;width: 750px;max-width: 100%;height: 500px;object-fit: cover;\" width=\"750\" height=\"1000\" src=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/09\/Pollo-a-la-plancha-con-ensalada-de-aguacate.jpg\" class=\"attachment-750x999999 size-750x999999\" alt=\"Pollo a la plancha con ensalada de aguacate\" srcset=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/09\/Pollo-a-la-plancha-con-ensalada-de-aguacate.jpg 1200w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/09\/Pollo-a-la-plancha-con-ensalada-de-aguacate-480x640.jpg 480w, https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/09\/Pollo-a-la-plancha-con-ensalada-de-aguacate-768x1024.jpg 768w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" data-attachment-id=\"8655\" data-permalink=\"https:\/\/www.laylita.com\/recetas\/pollo-a-la-plancha-con-ensalada-de-aguacate\/pollo-a-la-plancha-con-ensalada-de-aguacate\/\" data-orig-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/09\/Pollo-a-la-plancha-con-ensalada-de-aguacate.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"1\" data-image-title=\"Pollo a la plancha con ensalada de aguacate\" data-image-description=\"&lt;p&gt;Una receta f\u00e1cil y deliciosa de pollo a la plancha con ensalada de aguacate. Se prepara con pechugas de pollo marinadas en una mezcla de jugo de naranja, lim\u00f3n, ajo, comino, y or\u00e9gano. El pollo asado a la plancha se sirve con cilantro y ensaladita de aguacate.&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/09\/Pollo-a-la-plancha-con-ensalada-de-aguacate-768x1024.jpg\" \/><\/div>\n\t\n<\/div>\n<\/span>\n<div class=\"wprm-summary-container\">\n    <div class=\"wprm-recipe-name wprm-block-text-bold\">Pollo a la plancha con ensalada de aguacate<\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <div class=\"wprm-recipe-summary wprm-block-text-normal\"><span style=\"display: block;\">Una receta f\u00e1cil y deliciosa de pollo a la plancha con ensalada de aguacate. Se prepara con pechugas de pollo marinadas en una mezcla de jugo de naranja, lim\u00f3n, ajo, comino, y or\u00e9gano. <\/span><\/div>\n    <div class=\"wprm-spacer\"><\/div>\n    <a href=\"https:\/\/www.laylita.com\/recetas\/pollo-a-la-plancha-con-ensalada-de-aguacate\/\" style=\"color: #ffffff;background-color: #000000;border-color: #000000;border-radius: 5px;padding: 5px 5px;\" class=\"wprm-recipe-roundup-link wprm-recipe-link wprm-block-text-normal wprm-recipe-roundup-link-inline-button wprm-recipe-link-inline-button wprm-color-accent\" aria-label=\"Pollo a la plancha con ensalada de aguacate\">Ver esta Receta<\/a>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Receta f\u00e1cil para preparar pollo agridulce casero. Esta receta de pollo en salsa agridulce lleva pechuga o contramuslo de pollo, ajo, jengibre, pimientos dulces, cebolla, salsa de tomate, vinagre, salsa de soya, az\u00facar, huevo, harina, y aceite.<\/p>\n","protected":false},"author":19,"featured_media":13686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11,528,14,17,475,16],"tags":[],"class_list":["post-13666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aves","category-comida-reconfortante","category-norteamerica","category-plato-principal","category-pollo-o-gallina","category-asia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pollo Agridulce Chino | Laylita.com \u2013 Recetas de Cocina<\/title>\n<meta name=\"description\" content=\"Receta f\u00e1cil y casera para preparar pollo agridulce chino. La salsa agridulce tiene salsa de tomate, vinagre, salsa de soya, y az\u00facar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pollo Agridulce Chino | Laylita.com \u2013 Recetas de Cocina\" \/>\n<meta property=\"og:description\" content=\"Receta f\u00e1cil y casera para preparar pollo agridulce chino. La salsa agridulce tiene salsa de tomate, vinagre, salsa de soya, y az\u00facar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/\" \/>\n<meta property=\"og:site_name\" content=\"Laylita.com \u2013 Recetas de Cocina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LaylitaCom\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/LaylitaCom\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-14T16:13:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-24T14:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Layla Pujol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@laylita\" \/>\n<meta name=\"twitter:site\" content=\"@LaylaPujol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Layla Pujol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/\"},\"author\":{\"name\":\"Layla Pujol\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/person\\\/bb152c0e2cdff3c7b7ab8d516cd8f161\"},\"headline\":\"Pollo Agridulce Chino\",\"datePublished\":\"2022-01-14T16:13:00+00:00\",\"dateModified\":\"2024-09-24T14:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/\"},\"wordCount\":1218,\"commentCount\":6,\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg\",\"articleSection\":[\"Aves\",\"Comida reconfortante\",\"Norteamerica\",\"Plato principal\",\"Pollo o gallina\",\"Recetas con influencia Asi\u00e1tica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/\",\"name\":\"Pollo Agridulce Chino | Laylita.com \u2013 Recetas de Cocina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg\",\"datePublished\":\"2022-01-14T16:13:00+00:00\",\"dateModified\":\"2024-09-24T14:28:32+00:00\",\"description\":\"Receta f\u00e1cil y casera para preparar pollo agridulce chino. La salsa agridulce tiene salsa de tomate, vinagre, salsa de soya, y az\u00facar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Pollo en salsa agridulce al estilo chino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/pollo-agridulce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todas las recetas\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Por ingrediente\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/ingrediente\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Aves\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/ingrediente\\\/aves\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pollo o gallina\",\"item\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/category\\\/todo\\\/ingrediente\\\/aves\\\/pollo-o-gallina\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Pollo Agridulce Chino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#website\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\",\"name\":\"Laylita.com \u2013 Recetas de Cocina\",\"description\":\"Encuentra recetas deliciosas y f\u00e1ciles de cocina casera ecuatoriana, latina, e internacional en espa\u00f1ol - con videos y fotos paso a paso.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#organization\",\"name\":\"Laylita.com\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Laylita.com-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Laylita.com-logo.jpg\",\"width\":559,\"height\":558,\"caption\":\"Laylita.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LaylitaCom\",\"https:\\\/\\\/x.com\\\/LaylaPujol\",\"https:\\\/\\\/instagram.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/laylapujol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvNX-qrEsv2vNNzG2KXSRag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/#\\\/schema\\\/person\\\/bb152c0e2cdff3c7b7ab8d516cd8f161\",\"name\":\"Layla Pujol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg\",\"caption\":\"Layla Pujol\"},\"description\":\"Mi nombre es Layla Pujol, tambi\u00e9n conocida como Laylita, y soy ecuatoriana, aunque actualmente vivo en Europa. Muchas de mis recetas son inspiradas por la comida ecuatoriana, por la cocina americana-mexicana de mi mam\u00e1, quien creci\u00f3 en Nuevo M\u00e9xico, y tambi\u00e9n por la cocina de mi abuelita en Texas.\",\"sameAs\":[\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/quien-es-laylita\\\/\",\"https:\\\/\\\/www.facebook.com\\\/LaylitaCom\",\"https:\\\/\\\/x.com\\\/laylita\"],\"url\":\"https:\\\/\\\/www.laylita.com\\\/recetas\\\/author\\\/laylita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pollo Agridulce Chino | Laylita.com \u2013 Recetas de Cocina","description":"Receta f\u00e1cil y casera para preparar pollo agridulce chino. La salsa agridulce tiene salsa de tomate, vinagre, salsa de soya, y az\u00facar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/","og_locale":"es_ES","og_type":"article","og_title":"Pollo Agridulce Chino | Laylita.com \u2013 Recetas de Cocina","og_description":"Receta f\u00e1cil y casera para preparar pollo agridulce chino. La salsa agridulce tiene salsa de tomate, vinagre, salsa de soya, y az\u00facar.","og_url":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/","og_site_name":"Laylita.com \u2013 Recetas de Cocina","article_publisher":"https:\/\/www.facebook.com\/LaylitaCom","article_author":"https:\/\/www.facebook.com\/LaylitaCom","article_published_time":"2022-01-14T16:13:00+00:00","article_modified_time":"2024-09-24T14:28:32+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","type":"image\/jpeg"}],"author":"Layla Pujol","twitter_card":"summary_large_image","twitter_creator":"@laylita","twitter_site":"@LaylaPujol","twitter_misc":{"Escrito por":"Layla Pujol","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#article","isPartOf":{"@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/"},"author":{"name":"Layla Pujol","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/person\/bb152c0e2cdff3c7b7ab8d516cd8f161"},"headline":"Pollo Agridulce Chino","datePublished":"2022-01-14T16:13:00+00:00","dateModified":"2024-09-24T14:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/"},"wordCount":1218,"commentCount":6,"publisher":{"@id":"https:\/\/www.laylita.com\/recetas\/#organization"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","articleSection":["Aves","Comida reconfortante","Norteamerica","Plato principal","Pollo o gallina","Recetas con influencia Asi\u00e1tica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/","url":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/","name":"Pollo Agridulce Chino | Laylita.com \u2013 Recetas de Cocina","isPartOf":{"@id":"https:\/\/www.laylita.com\/recetas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#primaryimage"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#primaryimage"},"thumbnailUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","datePublished":"2022-01-14T16:13:00+00:00","dateModified":"2024-09-24T14:28:32+00:00","description":"Receta f\u00e1cil y casera para preparar pollo agridulce chino. La salsa agridulce tiene salsa de tomate, vinagre, salsa de soya, y az\u00facar.","breadcrumb":{"@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#primaryimage","url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","contentUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","width":1200,"height":800,"caption":"Pollo en salsa agridulce al estilo chino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.laylita.com\/recetas\/pollo-agridulce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.laylita.com\/recetas\/"},{"@type":"ListItem","position":2,"name":"Todas las recetas","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/"},{"@type":"ListItem","position":3,"name":"Por ingrediente","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/"},{"@type":"ListItem","position":4,"name":"Aves","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/aves\/"},{"@type":"ListItem","position":5,"name":"Pollo o gallina","item":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/aves\/pollo-o-gallina\/"},{"@type":"ListItem","position":6,"name":"Pollo Agridulce Chino"}]},{"@type":"WebSite","@id":"https:\/\/www.laylita.com\/recetas\/#website","url":"https:\/\/www.laylita.com\/recetas\/","name":"Laylita.com \u2013 Recetas de Cocina","description":"Encuentra recetas deliciosas y f\u00e1ciles de cocina casera ecuatoriana, latina, e internacional en espa\u00f1ol - con videos y fotos paso a paso.","publisher":{"@id":"https:\/\/www.laylita.com\/recetas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laylita.com\/recetas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.laylita.com\/recetas\/#organization","name":"Laylita.com","url":"https:\/\/www.laylita.com\/recetas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/logo\/image\/","url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/04\/Laylita.com-logo.jpg","contentUrl":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2019\/04\/Laylita.com-logo.jpg","width":559,"height":558,"caption":"Laylita.com"},"image":{"@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LaylitaCom","https:\/\/x.com\/LaylaPujol","https:\/\/instagram.com\/laylapujol\/","https:\/\/www.pinterest.com\/laylapujol\/","https:\/\/www.youtube.com\/channel\/UCvNX-qrEsv2vNNzG2KXSRag"]},{"@type":"Person","@id":"https:\/\/www.laylita.com\/recetas\/#\/schema\/person\/bb152c0e2cdff3c7b7ab8d516cd8f161","name":"Layla Pujol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eae083f7c23bda70dcf303e8e997bdc9d4b3ba76c4a977974741108bcd71d25b?s=96&d=mm&r=pg","caption":"Layla Pujol"},"description":"Mi nombre es Layla Pujol, tambi\u00e9n conocida como Laylita, y soy ecuatoriana, aunque actualmente vivo en Europa. Muchas de mis recetas son inspiradas por la comida ecuatoriana, por la cocina americana-mexicana de mi mam\u00e1, quien creci\u00f3 en Nuevo M\u00e9xico, y tambi\u00e9n por la cocina de mi abuelita en Texas.","sameAs":["https:\/\/www.laylita.com\/recetas\/quien-es-laylita\/","https:\/\/www.facebook.com\/LaylitaCom","https:\/\/x.com\/laylita"],"url":"https:\/\/www.laylita.com\/recetas\/author\/laylita\/"}]}},"featured_image_src":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","featured_image_src_square":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","author_info":{"display_name":"Layla Pujol","author_link":"https:\/\/www.laylita.com\/recetas\/author\/laylita\/"},"jetpack_featured_media_url":"https:\/\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/03\/Pollo-en-salsa-agridulce-al-estilo-chino.jpg","jetpack_shortlink":"https:\/\/wp.me\/pgQGB-3yq","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":14387,"url":"https:\/\/www.laylita.com\/recetas\/pollo-a-la-naranja\/","url_meta":{"origin":13666,"position":0},"title":"Pollo a la naranja","author":"Layla Pujol","date":"julio 2, 2022","format":false,"excerpt":"Receta del pollo a la naranja, este plato chino-americano consiste de pollo frito en una salsa espesa agridulce de naranja con jengibre y ajo.","rel":"","context":"En \u00abAves\u00bb","block_context":{"text":"Aves","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/aves\/"},"img":{"alt_text":"Receta casera del pollo a la naranja","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-casera-del-pollo-a-la-naranja.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-casera-del-pollo-a-la-naranja.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-casera-del-pollo-a-la-naranja.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-casera-del-pollo-a-la-naranja.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-casera-del-pollo-a-la-naranja.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":16289,"url":"https:\/\/www.laylita.com\/recetas\/arroz-chaufa\/","url_meta":{"origin":13666,"position":1},"title":"Arroz Chaufa","author":"Layla Pujol","date":"diciembre 14, 2022","format":false,"excerpt":"Receta casera del arroz chaufa peruano, esta variaci\u00f3n del arroz frito se prepara con pollo, jam\u00f3n, arroz, cebolla, ajo, jengibre (kion), huevos, sillao (salsa de soya), aceite, y m\u00e1s.","rel":"","context":"En \u00abArroces\u00bb","block_context":{"text":"Arroces","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/arroces\/"},"img":{"alt_text":"Receta del arroz chaufa peruano","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/12\/Receta-del-arroz-chaufa-peruano.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/12\/Receta-del-arroz-chaufa-peruano.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/12\/Receta-del-arroz-chaufa-peruano.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/12\/Receta-del-arroz-chaufa-peruano.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/12\/Receta-del-arroz-chaufa-peruano.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":14327,"url":"https:\/\/www.laylita.com\/recetas\/lo-mein-con-pollo-y-vegetales\/","url_meta":{"origin":13666,"position":2},"title":"Lo Mein con pollo y vegetales","author":"Layla Pujol","date":"junio 18, 2022","format":false,"excerpt":"Receta casera del Lo Mein con pollo y vegetales, este platillo asi\u00e1tico se prepara con fideos salteados con verduras y carne de pollo.","rel":"","context":"En \u00abComida reconfortante\u00bb","block_context":{"text":"Comida reconfortante","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/por-tipo\/comida-reconfortante\/"},"img":{"alt_text":"Receta del lo mein con pollo y vegetales","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-del-lo-mein-con-pollo-y-vegetales.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-del-lo-mein-con-pollo-y-vegetales.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-del-lo-mein-con-pollo-y-vegetales.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-del-lo-mein-con-pollo-y-vegetales.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2022\/06\/Receta-del-lo-mein-con-pollo-y-vegetales.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":17913,"url":"https:\/\/www.laylita.com\/recetas\/albondigas-de-pollo\/","url_meta":{"origin":13666,"position":3},"title":"Alb\u00f3ndigas de pollo","author":"Layla Pujol","date":"agosto 21, 2024","format":false,"excerpt":"Receta f\u00e1cil de las alb\u00f3ndigas de pollo caseras, se preparan con carne de pollo molida, migas de pan, ajo, or\u00e9gano, piment\u00f3n, y huevo. Se sirven con una deliciosa salsa de tomate.","rel":"","context":"En \u00abAves\u00bb","block_context":{"text":"Aves","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/aves\/"},"img":{"alt_text":"Un plato blanco con alb\u00f3ndigas de pollo en salsa de tomate","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2024\/08\/Como-preparar-albondigas-de-pollo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2024\/08\/Como-preparar-albondigas-de-pollo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2024\/08\/Como-preparar-albondigas-de-pollo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2024\/08\/Como-preparar-albondigas-de-pollo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/2024\/08\/Como-preparar-albondigas-de-pollo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1231,"url":"https:\/\/www.laylita.com\/recetas\/chaulafan-o-arroz-frito-de-pollo\/","url_meta":{"origin":13666,"position":4},"title":"Chaulafan o arroz frito de pollo","author":"Layla Pujol","date":"enero 20, 2012","format":false,"excerpt":"El chaulafan de pollo es la versi\u00f3n ecuatoriana del arroz frito chino. Se prepara con pollo, tocino, cebolla, ajo, pimientos, arvejas, zanahorias, huevos revueltos, pasas, especias y hierbas.","rel":"","context":"En \u00abArroces\u00bb","block_context":{"text":"Arroces","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/arroces\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/chaulafan-de-pollo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/chaulafan-de-pollo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/chaulafan-de-pollo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3695,"url":"https:\/\/www.laylita.com\/recetas\/empanadas-de-pollo-o-pavo\/","url_meta":{"origin":13666,"position":5},"title":"Empanadas de pollo o pavo","author":"Layla Pujol","date":"septiembre 17, 2013","format":false,"excerpt":"Receta casera para empanadas de pollo o pavo, con un delicioso relleno preparado con pollo o pavo, cebollas, ajo, pimientos, tomate, comino, or\u00e9gano y vinagre bals\u00e1mico.","rel":"","context":"En \u00abAves\u00bb","block_context":{"text":"Aves","link":"https:\/\/www.laylita.com\/recetas\/category\/todo\/ingrediente\/aves\/"},"img":{"alt_text":"Empanadas de pollo o pavo","src":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Empanadas-de-pollo-o-pavo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Empanadas-de-pollo-o-pavo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.laylita.com\/recetas\/wp-content\/uploads\/Empanadas-de-pollo-o-pavo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/13666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/comments?post=13666"}],"version-history":[{"count":8,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/13666\/revisions"}],"predecessor-version":[{"id":18216,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/posts\/13666\/revisions\/18216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/media\/13686"}],"wp:attachment":[{"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/media?parent=13666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/categories?post=13666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laylita.com\/recetas\/wp-json\/wp\/v2\/tags?post=13666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}